{"id":30914,"date":"2026-04-18T09:03:28","date_gmt":"2026-04-18T13:03:28","guid":{"rendered":"https:\/\/whsrn.org\/?p=30914"},"modified":"2026-04-18T10:25:23","modified_gmt":"2026-04-18T14:25:23","slug":"mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/","title":{"rendered":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776433587615{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<span data-contrast=\"auto\">Durante m\u00e1s de cien a\u00f1os, la producci\u00f3n artesanal de sal ha formado parte de la identidad de las comunidades del Pac\u00edfico hondure\u00f1o. Sin embargo, esta actividad siempre fue considerada un trabajo de hombres. <\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Crec\u00ed entre monta\u00f1as de sal y bandadas de aves migratorias. Recuerdo una frase que escuch\u00e9 muchas veces cuando era ni\u00f1a, pronunciada por mi padre, tambi\u00e9n productor salinero como mi abuelo: <\/span><i><span data-contrast=\"auto\">&#8220;La producci\u00f3n de sal no es para mujeres.&#8221; <\/span><\/i><span data-contrast=\"auto\">All\u00ed\u00a0decid\u00ed\u00a0demostrar\u00a0lo\u00a0contrario.<\/span><i><span data-contrast=\"auto\">\u00a0<\/span><\/i><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span>[\/vc_column_text][mk_blockquote font_family=&#8221;none&#8221;]\n<p style=\"text-align: left;\"><em>&#8220;Durante muchos a\u00f1os nos dijeron que este no era un trabajo para mujeres. Hoy estamos demostrando que s\u00ed lo es y que, adem\u00e1s, podemos producir sal mientras cuidamos la naturaleza.&#8221;<\/em><\/p>\n<p><span class=\"LineBreakBlob BlobObject DragDrop SCXW147608591 BCX0\"><span class=\"SCXW147608591 BCX0\"> &#8211; <\/span><\/span><span class=\"TextRun SCXW147608591 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW147608591 BCX0\">Carmen Banegas<\/span><\/span><span class=\"EOP Selected SCXW147608591 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:276}\">\u00a0<\/span>[\/mk_blockquote][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-1-julia-de-nina.-pie-de-foto-1-julia-en-la-salinera-familiar-de-nina.-foto-julia-salazar.jpg&#8221;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p><span class=\"NormalTextRun SCXW168770073 BCX0\">\u00a0Julia\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW168770073 BCX0\">e<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW168770073 BCX0\">n<\/span><span class=\"NormalTextRun SCXW168770073 BCX0\">\u00a0la\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW168770073 BCX0\">salinera<\/span><span class=\"NormalTextRun SCXW168770073 BCX0\">\u00a0familiar de\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SpellingErrorHighlight SCXW168770073 BCX0\">ni\u00f1a. <\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">Foto<\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">: Julia Salazar<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776461555608{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]\n<p style=\"text-align: left;\">Hoy soy Especialista en Producci\u00f3n Salinera y Conservaci\u00f3n de Aves Playeras en Manomet Conservation Sciences y en la Oficina Ejecutiva de la Red Hemisf\u00e9rica de Reservas para Aves Playeras (RHRAP\/ WHSRN por sus siglas en ingl\u00e9s), y lidero iniciativas que buscan integrar la producci\u00f3n de sal con la conservaci\u00f3n de las aves playeras en todo el hemisferio occidental. Desde el inicio, tuve claro que era importante visibilizar el rol de la mujer en la producci\u00f3n de sal. Hoy puedo decir con orgullo que ese cambio ya est\u00e1 ocurriendo.<\/p>\n<p style=\"text-align: left;\">Las fincas salineras del Pac\u00edfico de Honduras son refugios para miles de aves playeras que migran cada a\u00f1o por el continente. Estas aves encuentran en las lagunas salineras un lugar ideal para descansar y alimentarse durante sus largas migraciones. Lo que antes pasaba desapercibido para muchos productores, hoy se ha convertido en una raz\u00f3n m\u00e1s para cuidar estos espacios.<\/p>\n<p style=\"text-align: left;\">Estos esfuerzos no solo fortalecen la conservaci\u00f3n a nivel local, sino que tambi\u00e9n sientan las bases para una futura nominaci\u00f3n como sitio RHRAP\/WHSRN, consolidando un proceso progresivo que reconoce el valor del sitio y el compromiso de sus actores.<\/p>\n[\/vc_column_text][mk_blockquote font_family=&#8221;none&#8221;]<em>&#8220;Antes mir\u00e1bamos las aves y no sab\u00edamos mucho. Ahora sabemos que vienen de muy lejos y que nuestras salineras les ayudan a sobrevivir&#8221;<\/em><\/p>\n<p><span class=\"LineBreakBlob BlobObject DragDrop SCXW137601357 BCX0\"><span class=\"SCXW137601357 BCX0\">&#8211; <\/span><\/span><span class=\"TextRun SCXW137601357 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW137601357 BCX0\">Delia Hern\u00e1ndez<\/span><\/span><span class=\"EOP Selected SCXW137601357 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:276}\">\u00a0<\/span>[\/mk_blockquote][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/2.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/1.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\"><span class=\"TextRun SCXW127834507 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun CommentStart CommentHighlightPipeHovered CommentHighlightHovered SCXW127834507 BCX0\">Julia y dos productoras supervisando fincas salineras, mientras que en otra imagen se ve a las <span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">aves<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">playeras<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">aliment\u00e1ndose<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">en<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0lagunas de\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">producci\u00f3n<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">de<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW167702947 BCX0\">sal<\/span><span class=\"NormalTextRun SCXW167702947 BCX0\">.\u00a0<\/span><\/span><\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">Foto<\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">: Julia Salazar<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776461572413{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]En la Asociaci\u00f3n Nacional de Productores Salineros de Honduras (ASOPROSALH) hay m\u00e1s de 24 mujeres productoras due\u00f1as, administradoras y l\u00edderes del sector. Debido a la migraci\u00f3n laboral de personas, sobre todo de hombres, en busca de mejores oportunidades, muchas de las comunidades salineras ahora dependen de las mujeres, quienes han cubierto la demanda de mano de obra para la producci\u00f3n de sal. Muchas de esas mujeres heredaron las salineras de sus familias y decidieron continuar con un oficio que forma parte de la historia de sus comunidades.<\/p>\n<p>Bajo el proyecto \u201cSal Resiliente y Conservaci\u00f3n de Aves Playeras\u201d de Manomet Conservation Sciences con el apoyo financiero de la Iniciativa Darwin, cinco mujeres productoras, <span data-olk-copy-source=\"MessageBody\">cuyas fincas forman parte del piloto del proyecto Darwin, est\u00e1n dando pasos importantes hacia una producci\u00f3n m\u00e1s resiliente al clima y m\u00e1s amigable con el ambiente. <\/span>Est\u00e1n adecuando sus fincas salineras para incrementar la producci\u00f3n de sal y mejorar su calidad, al mismo tiempo que protegen los manglares y mejoran las condiciones para las aves playeras. Al mejorar las fincas salineras y su producci\u00f3n, estas mujeres tambi\u00e9n mejoran las condiciones de sus comunidades al ofrecer oportunidades de trabajo e ingresos justos.<\/p>\n<p>Estas y otras mujeres de la Asociaci\u00f3n de Productores Salineros de Honduras se han convertido en <span data-olk-copy-source=\"MessageBody\">observadoras<\/span> aficionadas, observando y registrando las aves que llegan a sus salineras. Toman fotograf\u00edas, comparten videos, ayudan a identificar especies y promueven peque\u00f1as acciones, como mantener las fincas limpias, mantener a sus mascotas lejos de las zonas que usan las aves playeras y evitar perturbarlas, convirti\u00e9ndose en aliadas clave para la conservaci\u00f3n.[\/vc_column_text][mk_blockquote font_family=&#8221;none&#8221;]\n<p style=\"text-align: left;\"><em><span class=\"NormalTextRun SCXW201478399 BCX0\">&#8220;<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">Ahora<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">,\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">cuando<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">llegan<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0las\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">aves<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">,\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">nos<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">ponemos<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">contentas<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">.\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">Sabemos<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">que<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">,\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">si<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">est\u00e1n<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">aqu\u00ed<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">, es\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">porque<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0la\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">salinera<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW201478399 BCX0\">est\u00e1<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0sana<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">.<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">&#8220;<\/span><span class=\"NormalTextRun SCXW201478399 BCX0\">\u00a0<\/span><\/em><\/p>\n<p><span class=\"LineBreakBlob BlobObject DragDrop SCXW212048046 BCX0\"><span class=\"SCXW212048046 BCX0\">&#8211; <\/span><\/span><span class=\"TextRun SCXW212048046 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SpellingErrorV2Themed SCXW212048046 BCX0\">Estreberta<\/span><span class=\"NormalTextRun SCXW212048046 BCX0\">\u00a0Hern\u00e1ndez Escobar<\/span><\/span><span class=\"EOP Selected SCXW212048046 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:276}\">\u00a0<\/span>[\/mk_blockquote][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/11.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/21.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\"><span class=\"NormalTextRun SCXW243952154 BCX0\"><span class=\"LineBreakBlob BlobObject DragDrop SCXW52048844 BCX0\">Izquierda: Aves playeras descansando a la orilla de las lagunas de las salineras; derecha: Trabajadores en las fincas salineras construyendo calentadoras.\u00a0<\/span><\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">Foto<\/span><span class=\"NormalTextRun SCXW174139601 BCX0\">: Julia Salazar<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_blockquote font_family=&#8221;none&#8221;]\n<p style=\"text-align: left;\"><em>\u201cGracias por permitirme formar parte de un proyecto en el que la naturaleza y el compromiso femenino se unen para conservar la vida. Ser mujer y contribuir a la conservaci\u00f3n de las aves es sembrar esperanza para las generaciones futuras, donde cada ave protegida es un recordatorio de que las peque\u00f1as acciones pueden crear grandes cambios.<\/em><\/p>\n<p><span data-olk-copy-source=\"MessageBody\"> &#8211; <span class=\"TextRun SCXW115790597 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW115790597 BCX0\"><span class=\"TextRun SCXW130277946 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW130277946 BCX0\">Magda Murillo<\/span><\/span><\/span><\/span><\/span>[\/mk_blockquote][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776426140374{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Al igual que las aves que visitan sus salinas, estas mujeres tambi\u00e9n han aprendido a adaptarse. La industria salinera enfrenta hoy grandes desaf\u00edos: el cambio clim\u00e1tico, las transformaciones del mercado y las dificultades para sostener la producci\u00f3n artesanal. Pero estas productoras contin\u00faan trabajando con resiliencia. En la Bah\u00eda de San Lorenzo, donde la sal y el mar se encuentran, estas mujeres est\u00e1n escribiendo una nueva historia. Una historia en la que la tradici\u00f3n, la conservaci\u00f3n y el liderazgo femenino caminan juntos, y donde, cada a\u00f1o, las aves playeras siguen encontrando un lugar donde llegar.<\/p>\n<p>Escuchar sus voces y ver a estas mujeres liderando el cambio tiene un significado especial para m\u00ed, y me indica que vamos por el camino adecuado.[\/vc_column_text][mk_blockquote font_family=&#8221;none&#8221;]\n<p style=\"text-align: left;\"><em>&#8220;Gracias por tomar en cuenta a las mujeres que, d\u00eda a d\u00eda, luchamos por el sustento de nuestros hogares, porque la producci\u00f3n de la sal es un trabajo digno, en el que la mano de obra es de personas que lo hacen con amor. Este proyecto est\u00e1 en manos de nuestro Se\u00f1or. Donde la naturaleza es maravillosa, nos hemos dado cuenta de que las aves playeras son las que m\u00e1s nos visitan en nuestros proyectos y disfrutamos de sus bellos colores\u201d, explica otra productora.&#8221;<\/em><\/p>\n<p>&#8211; Brenda Hern\u00e1ndez.[\/mk_blockquote][\/vc_column][\/vc_row][vc_row][vc_column][mk_image_slideshow images=&#8221;30933,30931,30934,30932,30935&#8243; image_width=&#8221;1748&#8243; image_height=&#8221;1240&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776433587615{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Durante m\u00e1s de cien a\u00f1os, la producci\u00f3n artesanal de sal ha formado parte de la identidad de las comunidades del Pac\u00edfico hondure\u00f1o. Sin embargo, esta actividad siempre fue considerada un trabajo de hombres. \u00a0 Crec\u00ed entre monta\u00f1as [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":30922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,506],"tags":[],"class_list":["post-30914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-noticias-de-la-oficina-ejecutiva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mujeres de Sal: Las guardianas de las aves playeras en Honduras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujeres de Sal: Las guardianas de las aves playeras en Honduras\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776433587615{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Durante m\u00e1s de cien a\u00f1os, la producci\u00f3n artesanal de sal ha formado parte de la identidad de las comunidades del Pac\u00edfico hondure\u00f1o. Sin embargo, esta actividad siempre fue considerada un trabajo de hombres. \u00a0 Crec\u00ed entre monta\u00f1as [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-18T13:03:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-18T14:25:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Salazar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Salazar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/\"},\"author\":{\"name\":\"Julia Salazar\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/f41912633c499fb9562c645abd8962ae\"},\"headline\":\"Mujeres de Sal: Las guardianas de las aves playeras en Honduras\",\"datePublished\":\"2026-04-18T13:03:28+00:00\",\"dateModified\":\"2026-04-18T14:25:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/\"},\"wordCount\":1480,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg\",\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Noticias de la Oficina Ejecutiva\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/\",\"name\":\"Mujeres de Sal: Las guardianas de las aves playeras en Honduras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg\",\"datePublished\":\"2026-04-18T13:03:28+00:00\",\"dateModified\":\"2026-04-18T14:25:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujeres de Sal: Las guardianas de las aves playeras en Honduras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/f41912633c499fb9562c645abd8962ae\",\"name\":\"Julia Salazar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g\",\"caption\":\"Julia Salazar\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/jsalazarmanomet-org\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/","og_locale":"es_ES","og_type":"article","og_title":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1776433587615{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Durante m\u00e1s de cien a\u00f1os, la producci\u00f3n artesanal de sal ha formado parte de la identidad de las comunidades del Pac\u00edfico hondure\u00f1o. Sin embargo, esta actividad siempre fue considerada un trabajo de hombres. \u00a0 Crec\u00ed entre monta\u00f1as [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2026-04-18T13:03:28+00:00","article_modified_time":"2026-04-18T14:25:23+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg","type":"image\/jpeg"}],"author":"Julia Salazar","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Julia Salazar","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/"},"author":{"name":"Julia Salazar","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/f41912633c499fb9562c645abd8962ae"},"headline":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras","datePublished":"2026-04-18T13:03:28+00:00","dateModified":"2026-04-18T14:25:23+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/"},"wordCount":1480,"commentCount":0,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg","articleSection":["Conservaci\u00f3n en Acci\u00f3n","Noticias de la Oficina Ejecutiva"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/","url":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/","name":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg","datePublished":"2026-04-18T13:03:28+00:00","dateModified":"2026-04-18T14:25:23+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2026\/04\/foto-4-mujer-trabajando-en-la-recoleccion-de-sal.-foto-julia-salazar-scaled-e1776432880848.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/mujeres-de-sal-las-guardianas-de-las-aves-playeras-en-honduras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Mujeres de Sal: Las guardianas de las aves playeras en Honduras"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/f41912633c499fb9562c645abd8962ae","name":"Julia Salazar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf3ab2c27f2475e82e0960136722c75bf5eb981dddc3fcaf6f3bdf56932406f9?s=96&d=mm&r=g","caption":"Julia Salazar"},"url":"https:\/\/whsrn.org\/es\/author\/jsalazarmanomet-org\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/30914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=30914"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/30914\/revisions"}],"predecessor-version":[{"id":31001,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/30914\/revisions\/31001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/30922"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=30914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=30914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=30914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}