{"id":28604,"date":"2025-03-12T21:45:03","date_gmt":"2025-03-12T21:45:03","guid":{"rendered":"https:\/\/whsrn.org\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/"},"modified":"2025-05-06T13:56:16","modified_gmt":"2025-05-06T13:56:16","slug":"un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/","title":{"rendered":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1746538518593{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/laguna-mar-chiquita\/\">Laguna Mar Chiquita<\/a>, un sitio de Importancia Hemisf\u00e9rica de la Red Hemisf\u00e9rica RHRAP\/WHSRN, fue recientemente escenario de un logro en la conservaci\u00f3n de aves playeras. Un equipo internacional de investigadores logr\u00f3 colocar radiotransmisores en ocho individuos de Falaropo Tricolor (<em data-start=\"459\" data-end=\"480\">Phalaropus tricolor<\/em>) en sus \u00e1reas de no reproducci\u00f3n\u2014un hecho in\u00e9dito en Am\u00e9rica del Sur. Este hito forma parte de un esfuerzo colaborativo m\u00e1s amplio para estudiar y proteger a esta especie, cuyas poblaciones enfrentan crecientes amenazas por la degradaci\u00f3n de su h\u00e1bitat.<\/p>\n<p class=\"\" data-start=\"731\" data-end=\"1439\">Los estudios del Falaropo Tricolor en <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/laguna-mar-chiquita\/\">Mar Chiquita<\/a> comenzaron en 2013 bajo el liderazgo de Marcela Castellino, Especialista en Lagos Salados y Conservaci\u00f3n de la Oficina Ejecutiva de RHRAP\/WHSRN, con monitoreos terrestres y estudios de h\u00e1bitat. Entre 2016 y 2019, se realizaron investigaciones sobre la ecolog\u00eda tr\u00f3fica de la especie, aunque los intentos de captura fueron infructuosos. En 2019, se consolidaron alianzas con <a href=\"https:\/\/www.avesargentinas.org.ar\">Aves Argentinas<\/a> y <a href=\"https:\/\/www.naturaargentina.org\">Natura Argentina<\/a> para realizar censos a\u00e9reos en el sitio. Dado que los falaropos son aves migratorias de largo alcance, los esfuerzos tambi\u00e9n se enfocaron en fortalecer conexiones internacionales con sitios clave para la especie, especialmente en Estados Unidos y Canad\u00e1.<\/p>\n<p class=\"\" data-start=\"1441\" data-end=\"2164\">Gracias a estas colaboraciones, desde 2023 <a href=\"http:\/\/www.manomet.org\">Manomet Conservation Sciences<\/a>, junto a <a href=\"https:\/\/www.oikonos.org\/es\">Oikonos<\/a> y Environment and Climate Change Canada (ECCC), ha estado coordinando investigaciones sobre los movimientos del Falaropo Tricolor. En 2024, se obtuvo un subsidio de la Ley de Conservaci\u00f3n de Aves Migratorias Neotropicales (NMBCA) para monitorear sus desplazamientos dentro y entre sitios e instalar estaciones receptoras del sistema <a href=\"https:\/\/motus.org\">MOTUS<\/a>. El proyecto se lleva a cabo en alianza con Fundaci\u00f3n L\u00edderes de Ansenuza (FLA), la Universidad de Connecticut (UConn), Oikonos Ecosystem of Knowledge, Environment and Climate Change Canada, la Divisi\u00f3n de Recursos de Vida Silvestre de Utah (UDWR), la Universidad de Saskatchewan (USak) y Thomson Rivers University.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/ezequiel-vivas-3.png&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/ezequiel-vivas-2.png&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]De izquierda a derecha: El primer Falaropo marcado en la historia de Am\u00e9rica del Sur, liberado en la costa de la laguna Mar Chiquita. Los NanoTags permiten a los investigadores estudiar la migraci\u00f3n y ecolog\u00eda de escala utilizando el sistema de rastreo de fauna silvestre Motus.[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1745934813023{margin-bottom: 0px !important;}&#8221;]\n<p class=\"\" data-start=\"2445\" data-end=\"3122\">El equipo ha trabajado en la colocaci\u00f3n de radiotransmisores a individuos de Falaropo Tricolor para rastrear sus movimientos migratorios, as\u00ed como en la instalaci\u00f3n de torres receptoras MOTUS en la laguna Mar Chiquita. Estas torres contribuir\u00e1n a revelar sitios de escala cr\u00edticos en el Hemisferio Occidental. MOTUS es una red internacional colaborativa de estaciones autom\u00e1ticas de telemetr\u00eda que detectan se\u00f1ales de radio de fauna marcada, incluyendo aves, murci\u00e9lagos e insectos, dentro de un radio de 18 km. Esta tecnolog\u00eda innovadora permite monitorear movimientos animales a gran escala y constituye una herramienta poderosa para avanzar en la ciencia de la conservaci\u00f3n.<\/p>\n<p class=\"\" data-start=\"3124\" data-end=\"3709\">Estos esfuerzos est\u00e1n liderados por Pablo Gigy Gregoret, Especialista en Conservaci\u00f3n de Lagos Salados de la Oficina Ejecutiva de WHSRN, quien contin\u00faa el legado iniciado por Marcela Castellino y trabaja en estrecha colaboraci\u00f3n con ella.<\/p>\n<p class=\"\" data-start=\"3124\" data-end=\"3709\"><em><strong data-start=\"3397\" data-end=\"3709\">\u201cEste paso hist\u00f3rico en el estudio del Falaropo Tricolor simboliza los lazos genuinos entre grupos de trabajo de distintas regiones y culturas con metas comunes. Trabajar en conservaci\u00f3n de especies en este contexto es realmente inspirador y se refleja en cada bandada que sobrevuela nuestros lagos salinos.\u201d &#8211; Pablo Gigy Gregoret<\/strong><\/em><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/ezequiel-vivas.png&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nEl equipo de investigaci\u00f3n coloc\u00f3 las redes de niebla, una de las t\u00e9cnicas utilizadas para capturar falaropos. <em>Foto: Pablo Gigy Gregoret<\/em><br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/7-2.png&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/4-1.png&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]La campa\u00f1a consiste en largos periodos en el campo en los que se instala un campamento t\u00e9cnico-cient\u00edfico en el que trabajan especialistas. <em>Fotos: Izquierda: Ezequiel Vivas, Derecha: Pablo Gigy Gregoret<\/em>.[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1746539769368{margin-bottom: 0px !important;}&#8221;]\n<p class=\"\" data-start=\"3914\" data-end=\"4411\">Las actividades en Mar Chiquita forman parte de un proyecto m\u00e1s amplio para enfrentar los desaf\u00edos de conservaci\u00f3n del Falaropo Tricolor y los lagos salados en todo el continente. Estos lagos constituyen una red de h\u00e1bitats insustituibles para cientos de miles de individuos durante sus ciclos anuales. Sin embargo, la especie muestra tendencias poblacionales en declive tanto a nivel local como hemisf\u00e9rico, lo que subraya la urgencia de implementar acciones de conservaci\u00f3n basadas en evidencia.<\/p>\n<p class=\"\" data-start=\"4413\" data-end=\"4788\"><strong>El trabajo en la laguna Mar Chiquita resalta el poder de la colaboraci\u00f3n y la innovaci\u00f3n para enfrentar los complejos desaf\u00edos de conservar a esta ave migratoria de largo alcance. Al combinar tecnolog\u00eda de punta con alianzas internacionales, este proyecto est\u00e1 allanando el camino hacia un futuro m\u00e1s prometedor para el Falaropo Tricolor y los ecosistemas de los que depende.<\/strong><\/p>\n<p class=\"\" data-start=\"4790\" data-end=\"5430\">En 2025 se prev\u00e9 marcar m\u00e1s individuos de Falaropo Tricolor en <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/chaplin-old-wives-reed-lakes\/\">Chaplin Lake<\/a> (Canad\u00e1) y <a href=\"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/\">Mono Lake <\/a>(EE.UU.), con el objetivo de instalar 15 transmisores nuevos en cada sitio. Aumentar el n\u00famero de transmisores es clave para obtener informaci\u00f3n sobre los movimientos de la especie a escalas local, regional y hemisf\u00e9rica. Conocer mejor el uso de h\u00e1bitat, la conectividad migratoria y la ecolog\u00eda migratoria permitir\u00e1 identificar sitios prioritarios y dise\u00f1ar estrategias de conservaci\u00f3n m\u00e1s efectivas. Investigaciones futuras tambi\u00e9n aportar\u00e1n informaci\u00f3n sobre la ecolog\u00eda reproductiva, de escala y de residencia no reproductiva de la especie.<\/p>\n<p class=\"\" data-start=\"5432\" data-end=\"6041\">La implementaci\u00f3n de estas actividades en Mar Chiquita fue posible gracias al apoyo financiero del NMBCA y el Servicio Forestal de EE.UU., en colaboraci\u00f3n con Environment and Climate Change Canada y el Fondo de Conservaci\u00f3n de Tracy Aviary. El trabajo de campo fue realizado por un equipo diverso compuesto por personal de la Oficina Ejecutiva de WHSRN, investigadores del Instituto de Investigaciones Marinas y Costeras de CONICET, un investigador de Thompson Rivers University, estudiantes de Weber State University y destacados participantes de la Academia de Conservaci\u00f3n de Fundaci\u00f3n L\u00edderes de Ansenuza.<\/p>\n<p class=\"\" data-start=\"6043\" data-end=\"6458\">Junto con socios locales, el equipo de Rutas Migratorias de Manomet y la Oficina Ejecutiva de WHSRN continuar\u00e1n trabajando para llenar vac\u00edos de informaci\u00f3n sobre la ecolog\u00eda migratoria, de escala y de sitio (reproductiva y no reproductiva) del Falaropo Tricolor en toda su distribuci\u00f3n, identificando sitios clave para la especie y generando informaci\u00f3n que contribuya a la toma de decisiones para su conservaci\u00f3n.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre el trabajo con el Falaropo Com\u00fan en Laguna Mar Chiquita, contactar con <a href=\"https:\/\/whsrn.org\/es\/team\/pablo-gigy-gregoret\/\">Pablo Gigy Gregoret<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]Foto de portada: Un grupo de Falaropo Com\u00fan. <em>Foto: Tetsu Esposito.<\/em>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1746538518593{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Laguna Mar Chiquita, un sitio de Importancia Hemisf\u00e9rica de la Red Hemisf\u00e9rica RHRAP\/WHSRN, fue recientemente escenario de un logro en la conservaci\u00f3n de aves playeras. Un equipo internacional de investigadores logr\u00f3 colocar radiotransmisores en ocho individuos [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":28565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[418,75,172,506,78,64,528],"tags":[],"class_list":["post-28604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conectando-sitios-es","category-conservacion-en-accion","category-monitoreo-de-poblaciones","category-noticias-de-la-oficina-ejecutiva","category-noticias-de-los-sitios","category-sin-categorizar","category-whsrn-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1746538518593{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Laguna Mar Chiquita, un sitio de Importancia Hemisf\u00e9rica de la Red Hemisf\u00e9rica RHRAP\/WHSRN, fue recientemente escenario de un logro en la conservaci\u00f3n de aves playeras. Un equipo internacional de investigadores logr\u00f3 colocar radiotransmisores en ocho individuos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T21:45:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T13:56:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/\"},\"author\":{\"name\":\"Andrea Ferreira\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c99f4586ddd69b25d743b18c11423e8e\"},\"headline\":\"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita\",\"datePublished\":\"2025-03-12T21:45:03+00:00\",\"dateModified\":\"2025-05-06T13:56:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/\"},\"wordCount\":1492,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg\",\"articleSection\":[\"Conectando Sitios\",\"Conservaci\u00f3n en Acci\u00f3n\",\"Monitoreo de Poblaciones\",\"Noticias de la Oficina Ejecutiva\",\"Noticias de los Sitios\",\"Sin categorizar\",\"WHSRN\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/\",\"name\":\"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg\",\"datePublished\":\"2025-03-12T21:45:03+00:00\",\"dateModified\":\"2025-05-06T13:56:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg\",\"width\":1023,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c99f4586ddd69b25d743b18c11423e8e\",\"name\":\"Andrea Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g\",\"caption\":\"Andrea Ferreira\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/andreaferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/","og_locale":"es_ES","og_type":"article","og_title":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1746538518593{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Laguna Mar Chiquita, un sitio de Importancia Hemisf\u00e9rica de la Red Hemisf\u00e9rica RHRAP\/WHSRN, fue recientemente escenario de un logro en la conservaci\u00f3n de aves playeras. Un equipo internacional de investigadores logr\u00f3 colocar radiotransmisores en ocho individuos [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2025-03-12T21:45:03+00:00","article_modified_time":"2025-05-06T13:56:16+00:00","og_image":[{"width":1023,"height":682,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg","type":"image\/jpeg"}],"author":"Andrea Ferreira","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Andrea Ferreira","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/"},"author":{"name":"Andrea Ferreira","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c99f4586ddd69b25d743b18c11423e8e"},"headline":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita","datePublished":"2025-03-12T21:45:03+00:00","dateModified":"2025-05-06T13:56:16+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/"},"wordCount":1492,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg","articleSection":["Conectando Sitios","Conservaci\u00f3n en Acci\u00f3n","Monitoreo de Poblaciones","Noticias de la Oficina Ejecutiva","Noticias de los Sitios","Sin categorizar","WHSRN"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/","url":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/","name":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg","datePublished":"2025-03-12T21:45:03+00:00","dateModified":"2025-05-06T13:56:16+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2025\/02\/wilsons-phalarope_tetsu-esposito_-paraguay-e1740419876838.jpg","width":1023,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/un-hito-historico-en-la-investigacion-del-falaropo-en-el-sitio-rhrap-laguna-mar-chiquita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Un Hito Hist\u00f3rico en la Investigaci\u00f3n del Falaropo Tricolor en Laguna Mar Chiquita"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c99f4586ddd69b25d743b18c11423e8e","name":"Andrea Ferreira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4532eb6f862aef7186f9f8e214c44e27bf4b99128b948177797faedc6e98b9c1?s=96&d=mm&r=g","caption":"Andrea Ferreira"},"url":"https:\/\/whsrn.org\/es\/author\/andreaferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/28604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=28604"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/28604\/revisions"}],"predecessor-version":[{"id":28865,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/28604\/revisions\/28865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/28565"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=28604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=28604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=28604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}