{"id":27606,"date":"2024-09-30T16:20:14","date_gmt":"2024-09-30T16:20:14","guid":{"rendered":"https:\/\/whsrn.org\/?p=27606"},"modified":"2024-10-07T23:36:31","modified_gmt":"2024-10-07T23:36:31","slug":"proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/","title":{"rendered":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1728344178655{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<span data-contrast=\"auto\">Reentr\u00e2ncias Maranhenses \u00e9 uma regi\u00e3o na costa ocidental do Maranh\u00e3o, nordeste do Brasil, nomeada em 1991 como um s\u00edtio da Rede Hemisf\u00e9rica de Reservas para Aves Lim\u00edcolas (WHSRN, sigla em ingl\u00eas). O n\u00famero de aves lim\u00edcolas migrat\u00f3rias utilizando a regi\u00e3o \u00e9 t\u00e3o grande (centenas de milhares!) que justificaram sua inclus\u00e3o na WHSRN como um S\u00edtio de Import\u00e2ncia Hemisf\u00e9rica \u2013 o \u00fanico no Brasil a ter esse status!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Com uma \u00e1rea de 2.680.911\u202fha, o <\/span><a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/reentrancias-maranhenses\/\"><span data-contrast=\"none\">s\u00edtio WHSRN das Reentr\u00e2ncias Maranhenses<\/span><\/a><span data-contrast=\"auto\">l abriga grande parte da popula\u00e7\u00e3o de quatro esp\u00e9cies de aves lim\u00edcolas migrat\u00f3rias das Am\u00e9ricas durante o ver\u00e3o austral: Baituru\u00e7u-de-axila-preta (&gt;\u202f50%, <\/span><i><span data-contrast=\"auto\">Pluvialis squatarola<\/span><\/i><span data-contrast=\"auto\">), Vira-pedras (&gt;\u202f70%, <\/span><i><span data-contrast=\"auto\">Arenaria interpres<\/span><\/i><span data-contrast=\"auto\">), Ma\u00e7arico-de-asa-branca (&gt;\u202f40%, <\/span><i><span data-contrast=\"auto\">Tringa semipalmata<\/span><\/i><span data-contrast=\"auto\">) Ma\u00e7arico-de-bico-torto (&gt;\u202f40%, <\/span><i><span data-contrast=\"auto\">Numenius phaeopus<\/span><\/i><span data-contrast=\"auto\">).\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">As caracter\u00edsticas das \u00e1reas \u00famidas dessa regi\u00e3o s\u00e3o singulares. O nome da regi\u00e3o, \u201creentr\u00e2ncias\u201d, refere-se \u00e0 costa extremamente recortada e baixa, com in\u00fameras ba\u00edas pontilhadas de ilhas, bancos de areia, canais de mar\u00e9, estu\u00e1rios e extensos manguezais, que proporcionam excelente habitat para nossas aves lim\u00edcolas. Essas reentr\u00e2ncias fazem parte da maior faixa cont\u00ednua de manguezais (721.000\u202fha) do planeta, que se estende do Maranh\u00e3o ao Amap\u00e1 e configura o <\/span><a href=\"https:\/\/rsis.ramsar.org\/ris\/2337\"><span data-contrast=\"none\">S\u00edtio Ramsar Estu\u00e1rio do Amazonas e seus Manguezais<\/span><\/a><span data-contrast=\"auto\">. N\u00e3o \u00e9 \u00e0 toa que tantas aves lim\u00edcolas escolhem esse s\u00edtio WHSRN para descansar no per\u00edodo n\u00e3o-reprodutivo, ou quando est\u00e3o migrando para os extremos norte e sul das Am\u00e9ricas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/paisaje.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/paisajes.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">As paisagens litor\u00e2neas das Reentr\u00e2ncias Maranhenses. <em>Foto:<\/em> Edgilson Pinheiro<\/p>\n<p class=\"font_9\">\n<\/div>\n<div id=\"comp-jlcre5gq\" class=\"wp2\" title=\"\" data-exact-height=\"450\" data-content-padding-horizontal=\"0\" data-content-padding-vertical=\"0\">\n<div id=\"comp-jlcre5gqlink\" class=\"wp2link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1727724336704{margin-bottom: 0px !important;}&#8221;]<span data-contrast=\"auto\">Desde sua nomea\u00e7\u00e3o como s\u00edtio WHSRN, as atividades relacionadas com aves lim\u00edcolas e sua conserva\u00e7\u00e3o estiveram focadas no monitoramento das popula\u00e7\u00f5es de aves (censos a\u00e9reos e terrestres) e \u00e0 marca\u00e7\u00e3o de milhares de indiv\u00edduos. Ainda h\u00e1 trabalho a ser feito com as comunidades locais e outras partes interessadas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Existem 15 munic\u00edpios dentro da \u00e1rea do s\u00edtio, com aproximadamente 250.000 habitantes. Grande parte da popula\u00e7\u00e3o que vive majoritariamente na regi\u00e3o litor\u00e2nea, tem ou teve contato com a pesca artesanal de peixe e camar\u00e3o. No entanto, apesar de dependerem economicamente das \u00e1reas \u00famidas e de vivenciarem esse ambiente em seu dia a dia, as comunidades e os representantes dos poderes p\u00fablicos locais t\u00eam um conhecimento limitado sobre as aves lim\u00edcolas migrat\u00f3rias. \u00c9 comum confundirem os grandes bandos de aves lim\u00edcolas com \u201cpassarinhos\u201d. Apenas aqueles que eventualmente ca\u00e7am essas aves conseguem reconhec\u00ea-las.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O Projeto Costa Norte do Brasil, desenvolvido pela SAVE Brasil em colabora\u00e7\u00e3o com o Escrit\u00f3rio Executivo da WHSRN e com apoio da Manomet Conservation Sciences, Environment Climate Change Canada e Funda\u00e7\u00e3o Bobolink, tem como objetivo conectar o s\u00edtio das Reentr\u00e2ncias Maranhenses, em sua totalidade \u2013 ambiente, aves e pessoas, \u00e0 WHSRN e \u00e0s estrat\u00e9gias nacionais e internacionais voltadas \u00e0 conserva\u00e7\u00e3o de aves lim\u00edcolas, ao mesmo tempo em que busca-se entender se h\u00e1 outros s\u00edtios potenciais na regi\u00e3o. As a\u00e7\u00f5es est\u00e3o alinhadas com o <\/span><a href=\"https:\/\/www.gov.br\/icmbio\/pt-br\/assuntos\/biodiversidade\/pan\/pan-aves-limicolas-migratorias\"><span data-contrast=\"none\">Plano de A\u00e7\u00e3o Nacional para a Conserva\u00e7\u00e3o das Aves Lim\u00edcolas Migrat\u00f3rias \u2013 PAN Aves Lim\u00edcolas<\/span><\/a><span data-contrast=\"auto\"> e com a Iniciativa <\/span><a href=\"https:\/\/atlanticflywayshorebirds.org\/pt-br\/\"><span data-contrast=\"none\">Pr\u00f3-Aves Lim\u00edcolas Migrat\u00f3rias na Rota do Atl\u00e2ntico \u2013 AFSI<\/span><\/a><span data-contrast=\"auto\">, sigla em ingl\u00eas.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/kids.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\"><span data-contrast=\"auto\">Escolas em Cururupu, junho de 2024. <em>Foto: <\/em>SAVE Brasil<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1727724388377{margin-bottom: 0px !important;}&#8221;]<span data-contrast=\"auto\">Nesse \u00faltimo ano, levamos \u00e0s comunidades tradicionais e poder p\u00fablico regional e local, informa\u00e7\u00f5es sobre a biologia das aves lim\u00edcolas, sua din\u00e2mica de migra\u00e7\u00e3o e a import\u00e2ncia das \u00e1reas \u00famidas para a manuten\u00e7\u00e3o de suas popula\u00e7\u00f5es. As a\u00e7\u00f5es focaram em tr\u00eas eixos principais: <\/span><i><span data-contrast=\"auto\">i<\/span><\/i><span data-contrast=\"auto\">) monitoramento (censo) de aves, <\/span><i><span data-contrast=\"auto\">ii<\/span><\/i><span data-contrast=\"auto\">) engajamento do poder p\u00fablico, de escolas e p\u00fablico geral, e <\/span><i><span data-contrast=\"auto\">iii<\/span><\/i><span data-contrast=\"auto\">) capacita\u00e7\u00e3o do setor de turismo local.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O monitoramento das popula\u00e7\u00f5es de aves lim\u00edcolas, feito mensalmente ao longo da Ba\u00eda de S\u00e3o Marcos e da Ba\u00eda de S\u00e3o Jos\u00e9, no Maranh\u00e3o, segue o protocolo do <\/span><a href=\"https:\/\/www.manomet.org\/project\/international-shorebird-survey\/\"><span data-contrast=\"none\">Monitoramento Internacional de Aves Lim\u00edcolas \u2013 ISS<\/span><\/a><span data-contrast=\"auto\"> (sigla em ingl\u00eas). Apesar das dificuldades log\u00edsticas inerentes \u00e0 regi\u00e3o, os censos s\u00e3o feitos em cinco locais na Ilha de S\u00e3o Lu\u00eds e j\u00e1 resultaram em quase100 listas submetidas ao eBird, sob o protocolo ISS. Janeiro \u00e9 o m\u00eas com maior abund\u00e2ncia total de aves lim\u00edcolas, e a esp\u00e9cie mais comum \u00e9 o ma\u00e7arico-rasteirinho (<\/span><i><span data-contrast=\"auto\">Calidris pusilla<\/span><\/i><span data-contrast=\"auto\">), com quase 14 mil aves contadas. No entanto, o ma\u00e7arico-de-asas-brancas (<\/span><i><span data-contrast=\"auto\">Tringa semipalmata<\/span><\/i><span data-contrast=\"auto\">) e o batuiru\u00e7u-de-axila-preta (<\/span><i><span data-contrast=\"auto\">Pluvialis squatarola<\/span><\/i><span data-contrast=\"auto\">) s\u00e3o mais comuns em mar\u00e7o.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O engajamento com o setor p\u00fablico foi feito atrav\u00e9s de uma s\u00e9rie de apresenta\u00e7\u00f5es e capacita\u00e7\u00e3o para os servidores de meio ambiente, educa\u00e7\u00e3o e turismo do estado e dos munic\u00edpios-chave para essa primeira etapa do projeto. Al\u00e9m de informa\u00e7\u00f5es sobre as aves e do grande valor da regi\u00e3o para elas, foi ressaltado para os participantes o valor agregado que as aves e seus ambientes conservados trazem para a regi\u00e3o, citando como exemplo o turismo. Enfatizou-se tamb\u00e9m a import\u00e2ncia da colabora\u00e7\u00e3o entre os setores p\u00fablico, privado e n\u00e3o-governamental para a efetiva conserva\u00e7\u00e3o das aves.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">As atividades nas escolas abusaram do l\u00fadico para ensinar \u00e0s crian\u00e7as da Educa\u00e7\u00e3o Infantil (3 a 5 anos) e Ensino Fundamental I (6 a 14 anos) o que s\u00e3o aves e quais suas necessidades. Molde de bicos em gesso, brincadeiras de alimenta\u00e7\u00e3o, bonecos de aves com diferentes plumagens e pesos e at\u00e9 tablets apresentando v\u00eddeos de aves lim\u00edcolas em seus ninhos, permitiram \u00e0s crian\u00e7as explorar diferentes sentidos enquanto aprendiam sobre as variadas adapta\u00e7\u00f5es que as aves lim\u00edcolas possuem para conseguir migrar e se alimentar nas praias e manguezais. Todas as crian\u00e7as que participaram das atividades (total de 662) receberam material de apoio para levar para casa e continuar o aprendizado junto com suas fam\u00edlias. O \u201cBicoletim\u201d, dando alus\u00e3o a um boletim das aves (\u201cbico\u201d), conta a hist\u00f3ria de Margot, uma vira-pedras (<\/span><i><span data-contrast=\"auto\">Arenaria interpres<\/span><\/i><span data-contrast=\"auto\">) encontrada em 2023 em Ilh\u00e9us, Bahia, e anilhada em New Jersey em 2013. A hist\u00f3ria \u00e9 narrada no formato de uma entrevista com Margot e faz o maior sucesso. O livro de atividades \u201cAves Lim\u00edcolas nas Am\u00e9ricas\u201d, parte integrante do <\/span><a href=\"https:\/\/whsrn.org\/discover-shorebirds\/\"><i><span data-contrast=\"none\">Discover Shorebird Curriculum<\/span><\/i><\/a><span data-contrast=\"auto\"> na vers\u00e3o em portugu\u00eas, tamb\u00e9m foi distribu\u00eddo e tornou-se uma incr\u00edvel ferramenta para as atividades com as crian\u00e7as. Em algumas escolas, por demanda da dire\u00e7\u00e3o, tamb\u00e9m foram feitas atividades pr\u00e1ticas de observa\u00e7\u00e3o de aves em campo. No total, foram atendidas seis escolas em dois munic\u00edpios \u2013 Raposa e Cururupu, Maranh\u00e3o.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/curriculum.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/ninos-curriculum.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5iy\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">O livro de atividades \u201cShorebirds in the Americas\u201d, que faz parte do curr\u00edculo Discover Shorebirds em portugu\u00eas, foi distribu\u00eddo e \u00e9 um excelente recurso para atividades com crian\u00e7as.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1727724414019{margin-bottom: 0px !important;}&#8221;]<span data-contrast=\"auto\">Para fazer o engajamento do p\u00fablico geral, aproveitamos datas comemorativos como o Dia das Crian\u00e7as e desenvolvemos atividades de observa\u00e7\u00e3o de aves lim\u00edcolas nas praias de Raposa e S\u00e3o Lu\u00eds, Maranh\u00e3o. Disponibilizando bin\u00f3culos e lunetas, orienta\u00e7\u00e3o para identifica\u00e7\u00e3o e compartilhamos com o p\u00fablico interessado curiosidades sobre a migra\u00e7\u00e3o. As quase 200 pessoas, entre crian\u00e7as, jovens e adultos, que participaram, nunca haviam ouvido falar de aves lim\u00edcolas. Durante a intera\u00e7\u00e3o, o p\u00fablico foi alertado sobre o impacto de carros circulando nas praias, assim como a presen\u00e7a de pets e lixo.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Foi tamb\u00e9m no munic\u00edpio de Raposa, Maranh\u00e3o, que aconteceu a capacita\u00e7\u00e3o do setor tur\u00edstico. A beleza natural dos ambientes e a procura, por parte dos turistas, a momentos de lazer e relaxamento na natureza, ofereceu a oportunidade de agregar valor aos passeios. O objetivo foi capacitar o guia tur\u00edstico e o condutor de embarca\u00e7\u00e3o a reconhecer as esp\u00e9cies utilizando uma prancha de identifica\u00e7\u00e3o e fornecer informa\u00e7\u00f5es sobre a biologia, migra\u00e7\u00e3o, amea\u00e7as, conserva\u00e7\u00e3o e import\u00e2ncia regional para as aves lim\u00edcolas. Dessa forma, promovemos a conscientiza\u00e7\u00e3o dos provedores de servi\u00e7o e tamb\u00e9m dos turistas. A capacita\u00e7\u00e3o de 20 provedores de passeios locais cunhou o novo \u201cturismo amigo das aves lim\u00edcolas\u201d. Pr\u00f3ximos passos incluem a\u00e7\u00f5es de capacita\u00e7\u00e3o junto aos hot\u00e9is, pousadas e restaurantes do munic\u00edpio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O caminho para uma integra\u00e7\u00e3o fluida com a rede \u00e9 longo, mas j\u00e1 \u00e9 poss\u00edvel ver que a curiosidade, admira\u00e7\u00e3o, e cuidado demonstrado pelas comunidades que participaram das a\u00e7\u00f5es do Projeto Costa Norte do Brasil abriram as portas para que as Reentr\u00e2ncias Maranhenses se apropriem do seu status de S\u00edtio de Import\u00e2ncia Hemisf\u00e9rica da WHSRN e utilizem as experi\u00eancias disponibilizadas pela rede e adaptadas sua realidade.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Nosso desejo \u00e9 que cada comunidade e cada um dos stakeholders identificados, reconhe\u00e7am as aves lim\u00edcolas e ensinem seus filhos e amigos sobre as incr\u00edveis jornadas que essas aves s\u00e3o capazes de fazer e que isso ecoe nas a\u00e7\u00f5es de cada um, aumentando o respeito \u00e0s aves e ao ambiente do qual elas dependem. Com isso, nossa miss\u00e3o de conservar \u00e1reas \u00famidas e aves lim\u00edcolas estaria finalmente sendo cumprida.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/bird-id.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/save.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5iy\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"html-h1 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1vvkbs x1heor9g x1qlqyl8 x1pd3egz x1a2a7pz\">Vinte prestadores de servi\u00e7os de turismo locais foram treinados e um novo termo, \u201cturismo favor\u00e1vel \u00e0s aves marinhas\u201d, foi criado.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto de capa:<\/strong> Vista a\u00e9rea de Reentr\u00e2ncias Maranhenses, Brasil. <em>Foto:<\/em> Edgilson Pinheiro[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1728344178655{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Reentr\u00e2ncias Maranhenses \u00e9 uma regi\u00e3o na costa ocidental do Maranh\u00e3o, nordeste do Brasil, nomeada em 1991 como um s\u00edtio da Rede Hemisf\u00e9rica de Reservas para Aves Lim\u00edcolas (WHSRN, sigla em ingl\u00eas). O n\u00famero de aves lim\u00edcolas [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":27538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,78,64,528],"tags":[],"class_list":["post-27606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-noticias-de-los-sitios","category-sin-categorizar","category-whsrn-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1728344178655{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Reentr\u00e2ncias Maranhenses \u00e9 uma regi\u00e3o na costa ocidental do Maranh\u00e3o, nordeste do Brasil, nomeada em 1991 como um s\u00edtio da Rede Hemisf\u00e9rica de Reservas para Aves Lim\u00edcolas (WHSRN, sigla em ingl\u00eas). O n\u00famero de aves lim\u00edcolas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T16:20:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T23:36:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliana Bosi de Almeida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliana Bosi de Almeida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/\"},\"author\":{\"name\":\"Juliana Bosi de Almeida\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/21c8627257691fae4ee4427fa40bcc9c\"},\"headline\":\"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades\",\"datePublished\":\"2024-09-30T16:20:14+00:00\",\"dateModified\":\"2024-10-07T23:36:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/\"},\"wordCount\":2146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/reentrancias.jpg\",\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Noticias de los Sitios\",\"Sin categorizar\",\"WHSRN\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/\",\"name\":\"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/reentrancias.jpg\",\"datePublished\":\"2024-09-30T16:20:14+00:00\",\"dateModified\":\"2024-10-07T23:36:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/reentrancias.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/reentrancias.jpg\",\"width\":2400,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/21c8627257691fae4ee4427fa40bcc9c\",\"name\":\"Juliana Bosi de Almeida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"caption\":\"Juliana Bosi de Almeida\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/jbosi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/","og_locale":"es_ES","og_type":"article","og_title":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1728344178655{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Reentr\u00e2ncias Maranhenses \u00e9 uma regi\u00e3o na costa ocidental do Maranh\u00e3o, nordeste do Brasil, nomeada em 1991 como um s\u00edtio da Rede Hemisf\u00e9rica de Reservas para Aves Lim\u00edcolas (WHSRN, sigla em ingl\u00eas). O n\u00famero de aves lim\u00edcolas [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2024-09-30T16:20:14+00:00","article_modified_time":"2024-10-07T23:36:31+00:00","og_image":[{"width":2400,"height":750,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg","type":"image\/jpeg"}],"author":"Juliana Bosi de Almeida","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Juliana Bosi de Almeida","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/"},"author":{"name":"Juliana Bosi de Almeida","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/21c8627257691fae4ee4427fa40bcc9c"},"headline":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades","datePublished":"2024-09-30T16:20:14+00:00","dateModified":"2024-10-07T23:36:31+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/"},"wordCount":2146,"commentCount":0,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg","articleSection":["Conservaci\u00f3n en Acci\u00f3n","Noticias de los Sitios","Sin categorizar","WHSRN"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/","url":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/","name":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg","datePublished":"2024-09-30T16:20:14+00:00","dateModified":"2024-10-07T23:36:31+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2024\/09\/reentrancias.jpg","width":2400,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/proyecto-costa-norte-de-brasil-conectar-la-red-a-un-sitio-rhrap-y-sus-comunidades-portugues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Projeto Costa Norte do Brasil: Conectando a Rede a um S\u00edtio WHSRN e Suas Comunidades"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/21c8627257691fae4ee4427fa40bcc9c","name":"Juliana Bosi de Almeida","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","caption":"Juliana Bosi de Almeida"},"url":"https:\/\/whsrn.org\/es\/author\/jbosi\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/27606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=27606"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/27606\/revisions"}],"predecessor-version":[{"id":27717,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/27606\/revisions\/27717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/27538"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=27606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=27606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=27606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}