{"id":24728,"date":"2023-07-25T16:31:49","date_gmt":"2023-07-25T16:31:49","guid":{"rendered":"https:\/\/whsrn.org\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/"},"modified":"2023-08-01T13:11:48","modified_gmt":"2023-08-01T13:11:48","slug":"fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/","title":{"rendered":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title font_family=&#8221;none&#8221;]\n<p style=\"text-align: center;\"><strong>Por: Marcela Castellino y Marina Castellino<\/strong><\/p>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829425757{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Las aves playeras migratorias no conocen de fronteras, ni de idiomas, ni de econom\u00eda o pol\u00edtica. Ellas simplemente conocen de humedales, de agua y de invertebrados, conocen de lugares que les proveen los recursos que necesitan en los diferentes momentos del a\u00f1o. Lugares que son su hogar a lo largo del complejo ciclo de vida que las lleva a viajar peri\u00f3dicamente cubriendo distancias que resultan incomprensibles para la mayor\u00eda de los seres vivos que habitan el planeta.<\/p>\n<p>El <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/mono-lake\/\">Lago Mono<\/a> y el <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/great-salt-lake\/\">Gran Lago Salado<\/a> son dos de esos hogares; son los m\u00e1s importantes para el Falaropo Com\u00fan (<em>Phalaropus tricolor<\/em>) entre su temporada reproductiva y el inicio de su migraci\u00f3n al sur. Es en estos dos lagos en los cuales un alt\u00edsimo porcentaje de la poblaci\u00f3n global de la especie se congrega y permanece algunas semanas del a\u00f1o. Aqu\u00ed los falaropos se cuentan de a miles o cientos de miles, y comen sin parar artemias y moscas de la sal mientras cambian sus colores reproductivos por el traje m\u00e1s discreto que vestir\u00e1n durante el verano austral. El destino final de la gran mayor\u00eda de estos falaropos ser\u00e1 la<a href=\"https:\/\/whsrn.org\/whsrn_sites\/laguna-mar-chiquita\/\"> Laguna Mar Chiquita<\/a>, que les dar\u00e1 la bienvenida con los primeros calores de la primavera austral.<\/p>\n<p>Pero a pesar de su belleza, su incre\u00edble capacidad de migrar miles de kil\u00f3metros y sus n\u00fameros relativamente abundantes, los falaropos est\u00e1n en riesgo. Los lagos salados de los cuales dependen hoy est\u00e1n en serio riesgo de conservaci\u00f3n. No hay otro tipo de ambiente que ofrezca a los falaropos los recursos que ellos necesitan. Y esto nos lleva a una simple pero dura conclusi\u00f3n: sin lagos salados ecol\u00f3gicamente saludables, nos quedaremos sin falaropos.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono2_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono1_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]Izquierda: Individuo no reproductores de Falaropo Com\u00fan. <em>Foto: Hugo Giraudo<\/em>. Derecha: Mural realizado por el artista cordob\u00e9s Franco \u201cVato\u201d Cervato en la localidad de Miramar de Ansenuza de la Provincia de C\u00f3rdoba en Argentina, dedicado al Falaropo Com\u00fan y a los lagos hermanados hace 30 a\u00f1os en el marco de la RHRAP\/WHSRN. <em>Foto: Fundaci\u00f3n L\u00edderes de Ansenuza.<\/em>[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829512461{margin-bottom: 0px !important;}&#8221;]Este llamado de atenci\u00f3n a la situaci\u00f3n de conservaci\u00f3n de los lagos salados, y por lo tanto a la vulnerabilidad de los falaropos, ha despertado el inter\u00e9s de numerosas personas y organizaciones que desde hace algunos a\u00f1os enfocan su trabajo en su conservaci\u00f3n, principalmente en estos tres lagos salados. Durante los \u00faltimos cuatro a\u00f1os, se ha trabajado fuertemente en el restablecimiento de los v\u00ednculos ya existentes entre socios de los tres lagos salados, y en la generaci\u00f3n de nuevos v\u00ednculos, entendiendo que la escala de la problem\u00e1tica requiere de la colaboraci\u00f3n de todos los involucrados aun cuando nos encontremos tan lejos geogr\u00e1ficamente.<\/p>\n<p>Hoy se comienzan a ver resultados de este trabajo constante y sostenido de vinculaci\u00f3n entre los lagos hermanos, que apoya y potencia el trabajo de los actores locales en cada sitio tejiendo a su vez una delicada trama que conecta y sostiene, que amplifica y expande el impacto de estas acciones a nivel hemisf\u00e9rico.<\/p>\n<p>El 18 de junio 2023 se realiz\u00f3, como parte del ya establecido y exitoso <a href=\"https:\/\/www.birdchautauqua.org\/\">Mono Basin Bird Chautauqua<\/a>, el primer <a href=\"https:\/\/www.birdchautauqua.org\/news-phalaropefest1\">Mono Basin Phalarope Festival<\/a>. Pero volvamos unos meses atr\u00e1s para entender de d\u00f3nde surgi\u00f3 la inspiraci\u00f3n para dicha celebraci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/3.jpeg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nLos visitantes participaron de diferentes salidas de campo durante las cuales conocieron el sitio y aprendieron sobre su ecolog\u00eda y conservaci\u00f3n de la mano de socios locales. <em>Foto: Marcela Castellino.<\/em><br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829576714{margin-bottom: 0px !important;}&#8221;]En diciembre de 2022 se realiz\u00f3 un<a href=\"https:\/\/whsrn.org\/es\/hermanamiento-entre-lagos-salados-un-acuerdo-que-se-ratifica-para-la-posteridad\/\"> evento internacional en la Laguna Mar Chiquita, C\u00f3rdoba (Argentina)<\/a>. El motivo de esta reuni\u00f3n fue la celebraci\u00f3n de los 30 a\u00f1os transcurridos desde el hermanamiento del Lago Mono, el Gran Lago Salado y la Laguna Mar Chiquita, tres lagos salados fundamentales para la supervivencia del Falaropo Com\u00fan. El eje principal de la reuni\u00f3n fue el fortalecimiento de los lazos entre personas trabajando en cada sitio a trav\u00e9s de la identificaci\u00f3n de oportunidades de apoyo, de capacitaciones, aprendizaje a partir de historias y experiencias, y de la colaboraci\u00f3n concreta en proyectos que apoyen la conservaci\u00f3n de estos maravillosos humedales.<\/p>\n<p>El broche de oro de este evento fue la inauguraci\u00f3n de un mural realizado por el artista cordob\u00e9s Franco \u201cVato\u201d Cervato, quien luego emprender\u00eda un viaje para pintar falaropos en Lee Vining (California) y Farmington (Utah).<\/p>\n<p>El evento termin\u00f3 con el compromiso de mantener estos lazos activos, y con la esperanza de retribuir la visita a quienes tuvieron la oportunidad de conocer Mar Chiquita.<\/p>\n<p>Esa oportunidad lleg\u00f3 de la mano de la celebraci\u00f3n de la vig\u00e9sima edici\u00f3n del Mono Basin Bird Chautauqua en junio de 2023, realizada en Lee Vining, una peque\u00f1a poblaci\u00f3n a orillas del Lago Mono. Una comitiva de visitantes de Argentina formada por personal del recientemente creado Parque Nacional Ansenuza, personal de Aves Argentinas, de Fundaci\u00f3n L\u00edderes de Ansenuza y de Manomet tuvieron la oportunidad de visitar el Lago Mono. A este grupo se sumaron tambi\u00e9n socios del Gran Lago Salado (Sagelland Collaborative y Audubon National Society), completando as\u00ed la presencia de representantes de los tres lagos salados hermanados.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono6_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono3_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nIzquierda: Firma de la ratificaci\u00f3n del hermanamiento entre los sitios, renovando el compromiso de trabajar juntos por su conservaci\u00f3n. Derecha: Grupo de representantes de los tres lagos salados hermanos que participaron de las celebraciones en Lago Mono. <em>Fotos: Ryan Carle.<\/em><br \/>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829654589{margin-bottom: 0px !important;}&#8221;]Adem\u00e1s de participar de las diferentes salidas de campo ofrecidas durante el Mono Basin Bird Chautauqua, el grupo de visitantes tuvo la oportunidad de conocer de la mano del equipo del Mono Lake Committee, de Oikonos Ecosystem Knowledge, de California State Parks y del Servicio Forestal de los Estados Unidos, detalles sobre la ecolog\u00eda del sitio, los desaf\u00edos y aprendizajes, sobre el manejo de \u00e1reas protegidas dentro de las que se encuentra este lago salado, Conocer tambi\u00e9n sobre el programa educativo que se lleva adelante desde hace muchos a\u00f1os en el sitio y tambi\u00e9n sobre las investigaciones y monitoreos que se est\u00e1n realizando en el sitio, con foco en el Falaropo Com\u00fan.<\/p>\n<p>En el marco de estas actividades, el 18 de junio fue el d\u00eda dedicado a la celebraci\u00f3n de los falaropos, en especial del Falaropo Com\u00fan. Esta peque\u00f1a ave migratoria cabe en la palma de una mano, pero puede atravesar el hemisferio completo en unos pocos d\u00edas con sus incre\u00edbles migraciones, record\u00e1ndonos la magia de la naturaleza, pero tambi\u00e9n su incre\u00edble fragilidad y nuestra responsabilidad de proteger para ellos los lagos salados a lo largo de su recorrido.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono5_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nDecenas de personas participaron del festival realizado en Lee Vining para celebrar a los falaropos y a los lagos salados. <em>Foto: Ryan Carle.<\/em><br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829752893{margin-bottom: 0px !important;}&#8221;]Dentro de las actividades del festival que se llev\u00f3 adelante en el Hess Park de la localidad de Lee Vining, la m\u00fasica y el arte se hicieron presentes en una jornada de sol que permiti\u00f3 la concurrencia de un gran n\u00famero de personas. Un concurso de disfraces de falaropos, un concurso de imitaci\u00f3n de cantos de aves, m\u00fasica en vivo y la presencia de stands de organizaciones y artistas locales formaron parte de la celebraci\u00f3n e invitaron a la comunidad a conocer m\u00e1s sobre las vinculaciones internacionales y los falaropos y sus haza\u00f1as migratorias.<\/p>\n<p>Entre lo m\u00e1s destacado de la jornada, se inauguraron tres murales dedicados al Falaropo Com\u00fan ubicados en diferentes paredes de la localidad de Lee Vining, y la firma por todos los presentes en la celebraci\u00f3n de la ratificaci\u00f3n del hermanamiento de los tres lagos salados, esta vez en el Lago Mono. Estos murales fueron realizados por el mismo artista cordob\u00e9s, Vato, que pint\u00f3 el mural en Mar Chiquita en diciembre 2022.<\/p>\n<p>Durante el tiempo compartido tambi\u00e9n se llevaron adelante reuniones de trabajo y se identificaron necesidades y futuras acciones, muchas de las cuales ya comienzan a concretarse. La posibilidad de compartir tiempo juntos y estrechar lazos es sin duda una poderosa fuente de inspiraci\u00f3n, renueva energ\u00edas y alimenta el compromiso entusiasta de quienes trabajan en conservaci\u00f3n. Estos lazos seguir\u00e1n creciendo y fortaleci\u00e9ndose, por el bien de los falaropos, la biodiversidad, las comunidades y por supuesto, los lagos salados.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto de portada: Falaropos en el lago Mono. Foto: David Carle<\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title font_family=&#8221;none&#8221;] Por: Marcela Castellino y Marina Castellino [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829425757{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Las aves playeras migratorias no conocen de fronteras, ni de idiomas, ni de econom\u00eda o pol\u00edtica. Ellas simplemente conocen de humedales, de agua y de invertebrados, conocen de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[418,75,175,78,528],"tags":[521,645,520],"class_list":["post-24728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conectando-sitios-es","category-conservacion-en-accion","category-eventos-festivales-celebraciones","category-noticias-de-los-sitios","category-whsrn-es","tag-falaropos","tag-festivales-de-aves-playeras","tag-lagos-salados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title font_family=&#8221;none&#8221;] Por: Marcela Castellino y Marina Castellino [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829425757{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Las aves playeras migratorias no conocen de fronteras, ni de idiomas, ni de econom\u00eda o pol\u00edtica. Ellas simplemente conocen de humedales, de agua y de invertebrados, conocen de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T16:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-01T13:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WHSRN Executive Office\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oficina Ejecutiva de WHSRN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/\"},\"author\":{\"name\":\"WHSRN Executive Office\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\"},\"headline\":\"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados\",\"datePublished\":\"2023-07-25T16:31:49+00:00\",\"dateModified\":\"2023-08-01T13:11:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/\"},\"wordCount\":1971,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mono-lake_banner.jpg\",\"keywords\":[\"Falaropos\",\"Festivales de Aves Playeras\",\"Lagos Salados\"],\"articleSection\":[\"Conectando Sitios\",\"Conservaci\u00f3n en Acci\u00f3n\",\"Eventos, Festivales y Celebraciones\",\"Noticias de los Sitios\",\"WHSRN\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/\",\"name\":\"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mono-lake_banner.jpg\",\"datePublished\":\"2023-07-25T16:31:49+00:00\",\"dateModified\":\"2023-08-01T13:11:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mono-lake_banner.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/mono-lake_banner.jpg\",\"width\":1500,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\",\"name\":\"WHSRN Executive Office\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"caption\":\"WHSRN Executive Office\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/whsrn-executive-office\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/","og_locale":"es_ES","og_type":"article","og_title":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title font_family=&#8221;none&#8221;] Por: Marcela Castellino y Marina Castellino [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1690829425757{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Las aves playeras migratorias no conocen de fronteras, ni de idiomas, ni de econom\u00eda o pol\u00edtica. Ellas simplemente conocen de humedales, de agua y de invertebrados, conocen de [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2023-07-25T16:31:49+00:00","article_modified_time":"2023-08-01T13:11:48+00:00","og_image":[{"width":1500,"height":555,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg","type":"image\/jpeg"}],"author":"WHSRN Executive Office","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Oficina Ejecutiva de WHSRN","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/"},"author":{"name":"WHSRN Executive Office","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1"},"headline":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados","datePublished":"2023-07-25T16:31:49+00:00","dateModified":"2023-08-01T13:11:48+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/"},"wordCount":1971,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg","keywords":["Falaropos","Festivales de Aves Playeras","Lagos Salados"],"articleSection":["Conectando Sitios","Conservaci\u00f3n en Acci\u00f3n","Eventos, Festivales y Celebraciones","Noticias de los Sitios","WHSRN"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/","url":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/","name":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg","datePublished":"2023-07-25T16:31:49+00:00","dateModified":"2023-08-01T13:11:48+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/07\/mono-lake_banner.jpg","width":1500,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/fortaleciendo-la-red-para-la-preservacion-de-los-lagos-salados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Fortaleciendo la Red para la Preservaci\u00f3n de los Lagos Salados"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1","name":"WHSRN Executive Office","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","caption":"WHSRN Executive Office"},"url":"https:\/\/whsrn.org\/es\/author\/whsrn-executive-office\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/24728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=24728"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/24728\/revisions"}],"predecessor-version":[{"id":24799,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/24728\/revisions\/24799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/24668"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=24728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=24728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=24728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}