{"id":23519,"date":"2023-02-14T23:36:55","date_gmt":"2023-02-14T23:36:55","guid":{"rendered":"https:\/\/whsrn.org\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/"},"modified":"2023-02-16T16:34:59","modified_gmt":"2023-02-16T16:34:59","slug":"el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/","title":{"rendered":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676466071161{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<a href=\"https:\/\/whsrn.org\/qa-dr-juliana-bosi-de-almeida-portuguese\/\">Leia esta hist\u00f3ria em portugu\u00eas aqui.<\/a><\/p>\n<p>Cuando pensamos en un playero, la primera imagen que nos viene a la mente es un ave con un pico largo que se alimenta sondeando la arena a lo largo de las costas. El Playerito Canela (<em>Calidris subruficollis<\/em>) no se ajusta a ese perfil. Raramente se encuentran en costas arenosas, tienen picos cortos, y se alimentan como chorlitos \u2014 sobre el suelo usando su vista para localizar presas. Esta especie es tan \u00fanica que hasta 2013 estuvo en su propio g\u00e9nero, <em>Tryngites<\/em>.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/winn_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]El Playerito Canela es un playero de tama\u00f1o mediano (18 cm \u2013 20 cm de largo) con un pico corto y oscuro, patas amarillas, y plumas caracter\u00edsticas debajo de las alas con color blanco plateado durante todo el a\u00f1o, mientras que en la cara y el vientre son de color amarillento. Foto: Brad Winn[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676509340334{margin-bottom: 0px !important;}&#8221;]Quiz\u00e1s el rasgo m\u00e1s singular es su comportamiento reproductivo, que una vez apareci\u00f3 en la serie de la BBC \u201cLa vida de las aves\u201d, presentada por David Attenborough. El Playerito Canela es el \u00fanico Scolopacidae en las Am\u00e9ricas que tiene un modelo de apareamiento comunal en la tundra \u00e1rtica, conocido como \u201c<em>leks<\/em>\u201d. Los machos dispersos en un <em>lek<\/em> defienden un peque\u00f1o territorio desde el que realizan sus exhibiciones de cortejo. Es una vista hermosa en la tundra \u00c1rtica. Desde la distancia tienes la impresi\u00f3n de que est\u00e1s viendo peque\u00f1os espejos que reflejan la luz del sol. Al mirar en detalle, te das cuenta de que estos reflejos provienen de la parte inferior de las alas de color blanco plateado de los machos que est\u00e1n mostrando una o ambas alas a las hembras que vuelan por encima o que observan desde el suelo a los machos. Despu\u00e9s de seleccionar un macho, las hembras van a construir nidos, incubar, y criar polluelos por s\u00ed mismas.<\/p>\n<p>Otro comportamiento inusual exhibido por la especie es la baja fidelidad de machos y hembras a los sitios de reproducci\u00f3n. Las aves playeras tienden a ser fieles al \u00e1rea donde se reproducen, con altas tasas de retorno a\u00f1o tras a\u00f1o. El Playerito Canela muestra una alta fidelidad a los pastizales <span class=\"TrackChangeTextInsertion TrackedChange TrackChangeHoverSelectColorRed SCXW69439696 BCX0\"><span class=\"TextRun SCXW69439696 BCX0\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun TrackChangeHoverSelectHighlightRed SCXW69439696 BCX0\">de <\/span><span class=\"NormalTextRun SpellingErrorV2Themed TrackChangeHoverSelectHighlightRed SCXW69439696 BCX0\">Am<\/span><\/span><\/span><span class=\"TrackChangeTextInsertion TrackedChange TrackChangeHoverSelectColorRed SCXW69439696 BCX0\"><span class=\"TextRun SCXW69439696 BCX0\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun SpellingErrorV2Themed TrackChangeHoverSelectHighlightRed SCXW69439696 BCX0\">erica<\/span><span class=\"NormalTextRun TrackChangeHoverSelectHighlightRed SCXW69439696 BCX0\"> del Sur <\/span><\/span><\/span> donde pasan la temporada no reproductiva, pero no a los sitios de tundra en los que se reproduce. Esta baja fidelidad combinada con la distribuci\u00f3n dispersa y espor\u00e1dica de la especie en las \u00e1reas de reproducci\u00f3n ha dificultado que los bi\u00f3logos de aves playeras determinen con precisi\u00f3n el tama\u00f1o de la poblaci\u00f3n, datos que son esenciales para las acciones de conservaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/arctic1_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/arctic2_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nLas alas levantadas de un macho de Playerito Canela son una vista hermosa. Fotos: <em>Shiloh Schulte<\/em><br \/>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676509623021{margin-bottom: 0px !important;}&#8221;]Incluso sin conocer con precisi\u00f3n el tama\u00f1o de su poblaci\u00f3n, sabemos que han sufrido una fuerte disminuci\u00f3n de la poblaci\u00f3n en el \u00faltimo siglo. La poblaci\u00f3n pas\u00f3 de cientos de miles o millones a principios de 1800 a un estimado de 35.000 a 78.000 aves. Esta disminuci\u00f3n se atribuye en gran parte a la caza comercial en las planicies centrales de Estados Unidos durante finales del siglo XIX y principios del XX. Actualmente, la especie se considera como \u2018casi amenazada\u2019 en la Lista Roja de Especies Amenazadas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) y ha sido incluida en la lista oficial de especies amenazadas de varios pa\u00edses de las Am\u00e9ricas.<\/p>\n<p>Durante los \u00faltimos veinte a\u00f1os, se ha estudiado a los Playeritos Canela a lo largo de su ciclo anual para obtener m\u00e1s informaci\u00f3n sobre sus rutas de migraci\u00f3n, sitios, y amenazas a las que se enfrentan. La especie migra a trav\u00e9s del interior (ruta Mid-continental) de las Am\u00e9ricas cuando vuela entre la tundra \u00e1rtica donde se reproducen (junio-agosto) y los pastizales pampeanos en el cono sur de Am\u00e9rica del Sur donde pasan la temporada no reproductiva (octubre-abril). Su migraci\u00f3n sigue una estrategia de vuelos cortos y paradas en muchos sitios durante su viaje (\u201chop and skip\u201d), a diferencia de otras especies que vuelan grandes distancias y se detienen en solo unos pocos sitios (\u201cjump\u201d), pero por un per\u00edodo m\u00e1s largo para acumular grandes cantidades de reserva de grasas.<\/p>\n<p>Durante el viaje hacia el sur, los Playeritos Canela migran a trav\u00e9s de las praderas occidentales de Canad\u00e1 y los Estados Unidos de Am\u00e9rica, deteni\u00e9ndose en Saskatchewan, Dakota del Norte, Dakota del Sur, Nebraska, Kansas, Oklahoma, y Texas. En Am\u00e9rica del Sur, las aves se detienen principalmente en Colombia, Bolivia, y Paraguay antes de llegar a los pastizales pampeanos costeros en Brasil, Uruguay, y Argentina. La migraci\u00f3n hacia el norte sigue un patr\u00f3n similar, aunque las aves realizan menos paradas en Am\u00e9rica del Sur. En Am\u00e9rica del Norte, utilizan paradas similares en las Grandes Llanuras antes de saltar al \u00c1rtico. En todos estos sitios, los Playeritos Canela se encuentran dispersos en peque\u00f1os n\u00fameros.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buffy-map_spanish.png&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nMapa ejemplo de recorrido hacia el norte y hacia el sur de un Playerito Canela.<br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676510440326{margin-bottom: 0px !important;}&#8221;]Esta estrategia de migraci\u00f3n tiene implicaciones para la conservaci\u00f3n de los Playeritos Canela, pues se extienden sobre un \u00e1rea extensa en varios sitios de parada en lugar de reunirse en grandes congregaciones en unos pocos sitios. Esta preocupaci\u00f3n de conservaci\u00f3n se complica a\u00fan m\u00e1s por el uso de la tierra, muchos de estos sitios son tierras que producen alimentos para las comunidades humanas. Afortunadamente, dependiendo de las pr\u00e1cticas adoptadas, los dos pueden coexistir dentro de ciertos sistemas productivos. Las estrategias de conservaci\u00f3n para la especie deben incluir la protecci\u00f3n del sitio, la implementaci\u00f3n de pr\u00e1cticas que beneficien tanto a la especie como a los productores, el desarrollo de pol\u00edticas que beneficien a la especie, y la colaboraci\u00f3n a escala de rutas migratorias.<\/p>\n<p>Durante las \u00faltimas d\u00e9cadas, varios sitios han sido identificados como importantes a lo largo de la ruta de migraci\u00f3n del Playerito Canela. Actualmente, nueve de estos sitios son parte de la Red Hemisf\u00e9rica de Reservas para Aves Playeras (RHRAP \/ WHSRN, por sus siglas en ingl\u00e9s). En Am\u00e9rica del Norte, <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/flint-hills\/\">Flint Hills<\/a> y <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/rainwater-basin\/\">Rainwater Basin<\/a> son Paisajes de Importancia Hemisf\u00e9rica para el Playerito Canela, y en Am\u00e9rica del Sur, la <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/barba-azul-nature-reserve\/\">Reserva Natural Barba Azul<\/a> (Bolivia) y las <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/sabanas-de-paz-de-ariporo-y-trinidad\/\">Sabanas de Paz de Ariporo y Trinidad<\/a> (Colombia) son Sitios de Importancia Regional. En algunos sitios, la colaboraci\u00f3n local entre propietarios de tierras y asociaciones de conservaci\u00f3n ha llevado al desarrollo e implementaci\u00f3n de pr\u00e1cticas que combinan la producci\u00f3n y la conservaci\u00f3n del h\u00e1bitat. Es necesario ampliar las colaboraciones exitosas como \u00e9stas a un enfoque de ruta migratoria para garantizar la conservaci\u00f3n del h\u00e1bitat para la mayor\u00eda de la poblaci\u00f3n de la especie.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/cattlebuff_monica.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/silva_newsletter.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]Izquierda: Peque\u00f1a bandada de Playeritos Canela con ganado pastando. <em>Foto: Monica Iglecia<\/em>. Derecha: Bandada de Playeritos Canela en Parque Nacional da Lagoa do Peixe. <em>Foto: Marco Silva<\/em>[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676509686800{margin-bottom: 0px !important;}&#8221;]La Iniciativa para la Conservaci\u00f3n de las Aves Playeras Migratorias en la Ruta Mid-continental (MSCI, por sus siglas en ingl\u00e9s) proporciona un enfoque de rutas migratorias para guiar las acciones de conservaci\u00f3n de las aves playeras, incluyendo al Playerito Canela. Su marco estrat\u00e9gico fue construido con la participaci\u00f3n de 242 instituciones representando a 18 pa\u00edses <span class=\"TextRun SCXW19090365 BCX0\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun CommentHighlightRest SCXW19090365 BCX0\">y territorios<\/span><\/span> de las Am\u00e9ricas. Proporciona un medio s\u00f3lido para mejorar la colaboraci\u00f3n y promover la conservaci\u00f3n de las aves playeras y los h\u00e1bitats a lo largo de estos pa\u00edses. El Playerito Canela es una de las especies focales que se benefician de esta nueva iniciativa hemisf\u00e9rica que se lanzar\u00e1 a finales del 2023.<\/p>\n<p>Con la conservaci\u00f3n enfocada a diferentes escalas, el futuro se ve mejor para el Playerito Canela. Los conservacionistas, las comunidades locales, y los propietarios de tierras comparten sus intereses y necesidades mientras trabajan juntos a escala local. Mientras tanto, la MSCI promover\u00e1 la conservaci\u00f3n a escala de ruta migratoria. Con el compromiso de tantas partes interesadas, existe la esperanza de que la especie contin\u00fae cautiv\u00e1ndonos con su comportamiento y exhibiciones \u00fanicas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto de portada: Bandada de Playeritos Canela. <em>Foto: Brad Winn<\/em><\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676466071161{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Leia esta hist\u00f3ria em portugu\u00eas aqui. Cuando pensamos en un playero, la primera imagen que nos viene a la mente es un ave con un pico largo que se alimenta sondeando la arena a lo largo [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":23460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[526,688],"tags":[60],"class_list":["post-23519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-whsrn","category-working-landscapes","tag-grasslands"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676466071161{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Leia esta hist\u00f3ria em portugu\u00eas aqui. Cuando pensamos en un playero, la primera imagen que nos viene a la mente es un ave con un pico largo que se alimenta sondeando la arena a lo largo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-14T23:36:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-16T16:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliana Bosi de Almeida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliana Bosi de Almeida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/\"},\"author\":{\"name\":\"Juliana Bosi de Almeida\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/21c8627257691fae4ee4427fa40bcc9c\"},\"headline\":\"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas\",\"datePublished\":\"2023-02-14T23:36:55+00:00\",\"dateModified\":\"2023-02-16T16:34:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/\"},\"wordCount\":1919,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/buff_banner.jpg\",\"keywords\":[\"Grasslands\"],\"articleSection\":[\"WHSRN\",\"Working Landscapes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/\",\"name\":\"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/buff_banner.jpg\",\"datePublished\":\"2023-02-14T23:36:55+00:00\",\"dateModified\":\"2023-02-16T16:34:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/buff_banner.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/buff_banner.jpg\",\"width\":1500,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/21c8627257691fae4ee4427fa40bcc9c\",\"name\":\"Juliana Bosi de Almeida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g\",\"caption\":\"Juliana Bosi de Almeida\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/jbosi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/","og_locale":"es_ES","og_type":"article","og_title":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1676466071161{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]Leia esta hist\u00f3ria em portugu\u00eas aqui. Cuando pensamos en un playero, la primera imagen que nos viene a la mente es un ave con un pico largo que se alimenta sondeando la arena a lo largo [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2023-02-14T23:36:55+00:00","article_modified_time":"2023-02-16T16:34:59+00:00","og_image":[{"width":1500,"height":555,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg","type":"image\/jpeg"}],"author":"Juliana Bosi de Almeida","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Juliana Bosi de Almeida","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/"},"author":{"name":"Juliana Bosi de Almeida","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/21c8627257691fae4ee4427fa40bcc9c"},"headline":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas","datePublished":"2023-02-14T23:36:55+00:00","dateModified":"2023-02-16T16:34:59+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/"},"wordCount":1919,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg","keywords":["Grasslands"],"articleSection":["WHSRN","Working Landscapes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/","url":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/","name":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg","datePublished":"2023-02-14T23:36:55+00:00","dateModified":"2023-02-16T16:34:59+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2023\/02\/buff_banner.jpg","width":1500,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/el-playerito-canela-un-ave-playera-unica-con-necesidades-de-conservacion-unicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Playerito Canela: Un Ave Playera \u00danica con Necesidades de Conservaci\u00f3n \u00danicas"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/21c8627257691fae4ee4427fa40bcc9c","name":"Juliana Bosi de Almeida","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf6ccf420710dc3f2875d9d62dd52e3328cdabf20f3dd1ed733c29642a365f94?s=96&d=mm&r=g","caption":"Juliana Bosi de Almeida"},"url":"https:\/\/whsrn.org\/es\/author\/jbosi\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/23519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=23519"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/23519\/revisions"}],"predecessor-version":[{"id":23601,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/23519\/revisions\/23601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/23460"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=23519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=23519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=23519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}