{"id":18498,"date":"2022-10-05T15:09:22","date_gmt":"2022-10-05T15:09:22","guid":{"rendered":"https:\/\/whsrn.org\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/"},"modified":"2022-10-06T13:46:29","modified_gmt":"2022-10-06T13:46:29","slug":"construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/","title":{"rendered":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664282200650{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]\n<h5 style=\"text-align: center;\"><strong>La creaci\u00f3n de &#8220;islas de aves&#8221; a partir de sedimentos dragados puede ayudar a compensar la p\u00e9rdida de h\u00e1bitat debida al clima a lo largo de la costa Atl\u00e1ntica.<\/strong><\/h5>\n[\/vc_column_text][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.manomet.org\/publication\/bird-island-experiment-georgia\/\">Publicado originalmente en manomet.org<\/a><\/p>\n<p style=\"text-align: center;\">Por: Kat J. McAlpine, Manomet<\/p>\n<\/div>\n<div id=\"comp-jlcre5gq\" class=\"wp2\" title=\"\" data-exact-height=\"450\" data-content-padding-horizontal=\"0\" data-content-padding-vertical=\"0\">\n<div id=\"comp-jlcre5gqlink\" class=\"wp2link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664281752019{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]El Cuerpo de Ingenieros del Ej\u00e9rcito de los EE. UU. (en adelante \u201cArmy Corps\u201d) mantiene el acceso a todas las v\u00edas fluviales, puertos, y muelles de nuestro pa\u00eds. Desde 1998 ha dragado casi 994 millones de metros c\u00fabicos (1,3 billones de yardas c\u00fabicas) de sedimentos a lo largo de la costa Atl\u00e1ntica para hacer frente a los procesos de erosi\u00f3n y deposici\u00f3n costera, mantener abierta la navegaci\u00f3n para embarcaciones y barcazas, y el comercio en general.<\/p>\n<p>&nbsp;<\/p>\n<p>Esa cantidad de sedimento es suficiente para pavimentar 92.000 kil\u00f3metros (57.000 millas) de autopista de cuatro carriles que podr\u00edan dar la vuelta a la l\u00ednea ecuatorial m\u00e1s de dos veces, dice <a href=\"https:\/\/manomet.org\/our-people\/mike-molnar\">Mike Molnar, Director de la Iniciativa de la Zona Costera de Manomet<\/a>. La mayor\u00eda de los materiales dragados suelen ser arrastrados a mar abierto y se depositan all\u00ed, lo que hasta ahora ha sido la opci\u00f3n m\u00e1s rentable para el \u201cArmy Corps\u201d. Sin embargo, Molnar ve ese material como oro. \u00c9l plantea que hay oportunidades para usar esos sedimentos con efectos beneficiosos: espec\u00edficamente, para aumentar y construir nuevos h\u00e1bitats para las aves playeras a lo largo de las costas y v\u00edas fluviales del Atl\u00e1ntico, una parte clave de la ruta migratoria del Atl\u00e1ntico por la que viajan las aves playeras durante sus migraciones anuales.<\/p>\n<p>Para poner a prueba la idea, esta primavera las autoridades estatales y federales usaron los sedimentos que el \u00a8Army Corps\u00a8 extrajo de una v\u00eda fluvial cercana. As\u00ed crearon una &#8220;isla de aves&#8221; en el <a href=\"https:\/\/whsrn.org\/es\/whsrn_sites\/altamaha-river-delta\/\">delta del r\u00edo Altamaha en Georgia<\/a>, con lo que se restaur\u00f3 una isla pantanosa erosionada.<\/p>\n<p>Tim Keyes, bi\u00f3logo de vida silvestre de la <a href=\"https:\/\/georgiawildlife.com\/\">Divisi\u00f3n de Recursos de Vida Silvestre de Georgia<\/a> quien supervisa la conservaci\u00f3n e investigaci\u00f3n de las aves en la costa, trabajando incansablemente con Kelie Moore, la coordinadora federal de coherencia de la <a href=\"https:\/\/coastalgadnr.org\/\">Divisi\u00f3n de Recursos Costeros<\/a> del estado, se acerc\u00f3 al Cuerpo de Ingenieros del Ej\u00e9rcito de los EE. UU. con la idea de dise\u00f1ar y crear una isla nueva. \u00c9ste ser\u00eda el primer proyecto de &#8220;mejor uso&#8221; de sedimentos costeros de Georgia. Tanto Keyes como Moore combinaron sus amplias experiencias en gesti\u00f3n costera para facilitar la creaci\u00f3n de este valioso h\u00e1bitat.<\/p>\n<p>&#8220;Anteriormente, el sedimento se consideraba un subproducto \u2014 con este proyecto, se est\u00e1 utilizando para aumentar el h\u00e1bitat natural de la isla&#8221;, dice Molnar. \u201cEl material dragado se ve como un recurso, en vez de un desecho\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La &#8220;isla de las aves&#8221; es una de las primeras de su tipo en crearse en Georgia. \u201cEs un mont\u00edculo de limo y arena al lado del canal del r\u00edo. Est\u00e1 destinado a ser transitorio y temporal, y se erosionar\u00e1\u201d, dice Molnar. Pero mientras tanto, la isla provee a las aves playeras \u2014 durante su migraci\u00f3n transcontinental de Am\u00e9rica del Sur al \u00c1rtico y luego de regreso \u2014 un lugar de descanso cr\u00edtico en un \u00e1rea donde la costa se ha erosionado r\u00e1pidamente por las inundaciones provocadas por el cambio clim\u00e1tico y el aumento del nivel del mar.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/single-red-knot.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nEspecies c\u00f3mo el Playero Rojizo dependen de las playas del Atl\u00e1ntico durante su migraci\u00f3n. <em>Foto: Brad Winn.<\/em><br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664281875012{margin-bottom: 0px !important;}&#8221;]El proyecto se puso en marcha gracias a la coordinaci\u00f3n de bi\u00f3logos de aves playeras, agencias de vida silvestre estatales y federales, socios estatales, ONG, y el \u201cArmy Corps\u201d, quienes se reunieron en talleres dise\u00f1ados para generar ideas sobre formas beneficiosas de aprovechar los sedimentos dragados. \u201cSe pueden lograr cosas buenas cuando tienes los actores correctos en la mesa\u201d, dice Molnar. \u201cSe trata tanto de la coordinaci\u00f3n como de la gesti\u00f3n de recursos, y estos talleres ayudaron a reunirlos a todos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Los talleres, financiados en parte por la Fundaci\u00f3n Nacional de Pesca y Vida Silvestre y la Fundaci\u00f3n R. Howard Dobbs, Jr., hasta ahora se han llevado a cabo en Georgia, Virginia, Nueva Jersey, Delaware, y Massachusetts, y han sido copatrocinados por personal de la Organizaci\u00f3n de Estados Costeros. El primer taller de Georgia, realizado en 2019, cont\u00f3 con la asistencia de m\u00e1s de 30 participantes. \u201cA partir de esas conversaciones, identificamos proyectos potenciales y resultaron en muchos emparejamientos, como me gusta llamarlo\u201d, dice Molnar.<\/p>\n<p>&nbsp;<\/p>\n<p>La isla de aves de Georgia puede ser ef\u00edmera, pero el proyecto de esta primavera sirvi\u00f3 como una prueba de concepto exitosa, mostrando que cuando los socios se coordinan, el material dragado se puede colocar en \u00e1reas que podr\u00edan beneficiar desde la restauraci\u00f3n de la costa hasta apoyar a las aves playeras y otra vida silvestre local.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEl uso beneficioso de los sedimentos de dragado no es un concepto nuevo\u201d, dice Laurel Reichold del \u201cArmy Corps\u201d, directora del Centro Regional de Experiencia en Manejo de Sedimentos del Atl\u00e1ntico Sur, \u201cpero la construcci\u00f3n de islas de h\u00e1bitats para las aves y la restauraci\u00f3n de marismas con sedimentos de dragado son bastante nuevos para nuestra regi\u00f3n; y se necesita una comunidad de expertos para formular planes exitosos. Esperamos continuar la colaboraci\u00f3n con Manomet y otros para ampliar la implementaci\u00f3n de este tipo de proyectos en toda la regi\u00f3n\u201d.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto de Portada:<\/strong> <strong>Un grupo de aves playeras reunido antes de ir a descansar a lo largo del delta del r\u00edo Altamaha, Georgia. <em>Foto: Brad Winn<\/em><\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664282200650{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;] La creaci\u00f3n de &#8220;islas de aves&#8221; a partir de sedimentos dragados puede ayudar a compensar la p\u00e9rdida de h\u00e1bitat debida al clima a lo largo de la costa Atl\u00e1ntica. [\/vc_column_text][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":18324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,77],"tags":[],"class_list":["post-18498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-problemas-de-conservacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664282200650{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;] La creaci\u00f3n de &#8220;islas de aves&#8221; a partir de sedimentos dragados puede ayudar a compensar la p\u00e9rdida de h\u00e1bitat debida al clima a lo largo de la costa Atl\u00e1ntica. [\/vc_column_text][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T15:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T13:46:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guest Author\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor Invitado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/\"},\"author\":{\"name\":\"Guest Author\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/99cbcafd1a567d9e50eed8268171f392\"},\"headline\":\"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial\",\"datePublished\":\"2022-10-05T15:09:22+00:00\",\"dateModified\":\"2022-10-06T13:46:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/\"},\"wordCount\":1172,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg\",\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Problemas de Conservaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/\",\"name\":\"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg\",\"datePublished\":\"2022-10-05T15:09:22+00:00\",\"dateModified\":\"2022-10-06T13:46:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/99cbcafd1a567d9e50eed8268171f392\",\"name\":\"Guest Author\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"caption\":\"Guest Author\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/guest_author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1664282200650{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;] La creaci\u00f3n de &#8220;islas de aves&#8221; a partir de sedimentos dragados puede ayudar a compensar la p\u00e9rdida de h\u00e1bitat debida al clima a lo largo de la costa Atl\u00e1ntica. [\/vc_column_text][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2022-10-05T15:09:22+00:00","article_modified_time":"2022-10-06T13:46:29+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg","type":"image\/jpeg"}],"author":"Guest Author","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Autor Invitado","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/"},"author":{"name":"Guest Author","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/99cbcafd1a567d9e50eed8268171f392"},"headline":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial","datePublished":"2022-10-05T15:09:22+00:00","dateModified":"2022-10-06T13:46:29+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/"},"wordCount":1172,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg","articleSection":["Conservaci\u00f3n en Acci\u00f3n","Problemas de Conservaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/","url":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/","name":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg","datePublished":"2022-10-05T15:09:22+00:00","dateModified":"2022-10-06T13:46:29+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/09\/pre-night-roost-gathering-altamaha-river-delta-georgia-usa-brad-winn-scaled-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/construir-una-isla-para-las-aves-playeras-un-experimento-en-georgia-muestra-su-potencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfConstruir una Isla para las Aves Playeras? Un Experimento en Georgia Muestra su Potencial"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/99cbcafd1a567d9e50eed8268171f392","name":"Guest Author","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","caption":"Guest Author"},"url":"https:\/\/whsrn.org\/es\/author\/guest_author\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/18498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=18498"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/18498\/revisions"}],"predecessor-version":[{"id":18527,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/18498\/revisions\/18527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/18324"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=18498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=18498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=18498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}