{"id":17037,"date":"2022-02-28T19:08:01","date_gmt":"2022-02-28T19:08:01","guid":{"rendered":"https:\/\/whsrn.org\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/"},"modified":"2022-03-02T15:51:09","modified_gmt":"2022-03-02T15:51:09","slug":"impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/","title":{"rendered":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\" style=\"text-align: center;\"><strong>Por Germ\u00e1n Leyva &#8211; Centro de Investigaci\u00f3n en Alimentaci\u00f3n y Desarrollo \u2013 CIAD. Sonora, M\u00e9xico<\/strong><\/p>\n<\/div>\n<div id=\"comp-jlcre5gq\" class=\"wp2\" title=\"\" data-exact-height=\"450\" data-content-padding-horizontal=\"0\" data-content-padding-vertical=\"0\">\n<div id=\"comp-jlcre5gqlink\" class=\"wp2link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236066252{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]De los grupos biol\u00f3gicos m\u00e1s afectados por la degradaci\u00f3n de los humedales costeros se encuentran las aves playeras; al estar experimentando una p\u00e9rdida de poblaci\u00f3n constante y pronunciada. La zona costera ha sido impactada por actividades humanas, como la agricultura, la acuicultura, el turismo y el desarrollo urbano. Sin embargo; existen actividades productivas que ofrecen sitios alternativos, siendo una oportunidad ante h\u00e1bitats naturales perturbados. Las salineras industriales son importantes para las aves playeras durante el abastecimiento de energ\u00eda, pudiendo haber eventos en que la densidad de individuos es mayor a la de humedales naturales.<\/p>\n<p>La salina de Lobos (&gt;1.000 hect\u00e1reas) en el sur de Sonora, M\u00e9xico, es una zona de gran importancia para las aves playeras por su conectividad con el sitio Bah\u00eda de Lobos, designado como Sitio de Importancia Regional dentro de la Red Hemisf\u00e9rica de Reservas para Aves Playeras (RHRAP\/ WHSRN por sus siglas en ingl\u00e9s) desde octubre de 2018. En la salina, los estanques de evaporaci\u00f3n producen abundantes invertebrados como el camar\u00f3n de salmuera (<em>Artemia spp<\/em>.) y la mosca de la sal (<em>Ephydra spp<\/em>.) que sirven de alimento para las aves playeras<strong>.<\/strong> Al mismo tiempo, las grandes extensiones de agua facilitan el vuelo y la evasi\u00f3n de depredadores, mientras que los estanques poco profundos crean un ambiente favorable para descansar y \u00a0algunas especies tambi\u00e9n usan los bordos, islas y llanos para anidar.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos1_maquinariasal.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos2_salinalobosl.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Izquierda: Maquinaria trabajando en la cosecha de sal. Derecha: Panor\u00e1mica de Salina de Lobos<em>. <\/em><em>Foto: Germ\u00e1n Leyva-Garc\u00eda.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236141287{margin-bottom: 0px !important;}&#8221;]En 2020 y gracias al apoyo del Sonoran Joint Venture (SJV) desarrollamos el proyecto \u201cImpulsando acciones de conservaci\u00f3n para aves acu\u00e1ticas en el sur de Sonora\u201d, para llevar a cabo la l\u00ednea base y proponer acciones conjuntas de manejo del h\u00e1bitat. El proyecto estuvo coordinado por el Centro de Investigaci\u00f3n en Alimentaci\u00f3n y Desarrollo (CIAD) y tuvo diversos socios como la propia empresa, personas de la comunidad de Bah\u00eda de Lobos, el Centro de Investigaci\u00f3n Cient\u00edfica y de Educaci\u00f3n Superior de Ensenada (CICESE), el Instituto de Ciencias del Mar y Limnolog\u00eda (ICMyL-UNAM) y el Instituto tecnol\u00f3gico del Valle del Yaqui (ITVY).<\/p>\n<p>En la primera etapa del proyecto capacitamos al \u00a0personal de la salinera y a dos estudiantes de biolog\u00eda del ITVY para el monitoreo de aves. Registramos \u00a0un total de 55 especies durante la migraci\u00f3n (octubre-enero), de las cuales 44% fueron aves playeras (23 especies). La especie de mayor abundancia fue el Playero Occidental (<em>Calidris mauri<\/em>), que, sumada a Playero Diminuto (<em>C. minutilla<\/em>), Playero Dorso Rojo (<em>C. alpina<\/em>)<em>, <\/em>y Playero Blanco (<em>C. alba<\/em>) fueron m\u00e1s de 6.000 individuos. Tambi\u00e9n registramos 70 individuos de Chorlo Nevado (<em>Charadrius nivosus<\/em>), especie amenazada en M\u00e9xico. Otras especies importantes fueron Falaropo Cuello Rojo (<em>Phalaropus lobatus<\/em>) en oto\u00f1o, y Falaropo Pico Largo (<em>Phalaropus tricolor<\/em>) en primavera, con hasta 250 y 800 individuos, respectivamente. Otros grupos importantes fueron los patos (Anatidae) y zambullidores (Podicipedidae).[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos3_falaropos.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos4_bandada.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]Izquierda: Falaropos Cuello Rojo. Derecha: Parvada de Falaropos Pico Largo.<em> Fotos: Germ\u00e1n Leyva-Garc\u00eda.<\/em>[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236190470{margin-bottom: 0px !important;}&#8221;]Tambi\u00e9n realizamos un seguimiento de las aves playeras que utilizan la salina durante la temporada reproductiva registrando cinco especies: 34 parejas de Chorlo Nevado, 34 parejas de Chorlo Pico Grueso (<em>Charadrius wilsonia<\/em>), 21 parejas de Monjita Americana (<em>Himantopus mexicanus<\/em>), 3 parejas de Ostrero Americano (<em>Haematopus palliatus<\/em>) y 8 parejas de Charr\u00e1n Menor (<em>Sternula antillarum<\/em>). \u00a0En las dos temporadas del monitoreo observamos algunas amenazas. En migraci\u00f3n, por ejemplo, registramos la presencia de rapaces en los sitios de descanso y alimentaci\u00f3n, teniendo al Halc\u00f3n Peregrino (<em>Falco peregrinus<\/em>) como el principal depredador. En la temporada reproductiva las amenazas fueron la inundaci\u00f3n por mareas altas extremas y lluvias tempranas, presencia de perros y tr\u00e1fico de maquinaria pesada en algunas zonas.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos5_pollitos.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\nPollos de Monjita Americana. <em>Foto: Germ\u00e1n Leyva-Garc\u00eda.<\/em><br \/>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236209205{margin-bottom: 0px !important;}&#8221;]En la segunda etapa del proyecto realizamos reuniones de trabajo entre los socios para determinar las acciones necesarias para la conservaci\u00f3n de las especies de aves playeras registradas en la salina. Estas reuniones permitieron llegar a algunos acuerdos de manejo, entre los que se encuentran algunas actividades enfocadas en la protecci\u00f3n de zonas de anidaci\u00f3n c\u00f3mo la construcci\u00f3n de un bordo de contenci\u00f3n para proteger un \u00e1rea de anidaci\u00f3n de 12.6 hect\u00e1reas sujeta a inundaci\u00f3n, la creaci\u00f3n de mont\u00edculos de sustrato para aumentar la altura de la zona de anidaci\u00f3n y la instalaci\u00f3n de jaulas de exclusi\u00f3n para la protecci\u00f3n de nidos ante depredadores. Adem\u00e1s, se propuso la realizaci\u00f3n de material de educaci\u00f3n ambiental y el uso de plataformas de <em>eBird<\/em> y <em>Inaturalist<\/em>, la planeaci\u00f3n del primer festival de aves de Bah\u00eda de Lobos, as\u00ed como la implementaci\u00f3n de un programa de monitoreo de aves a largo plazo.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos6_reuniones.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Trabajo de campo con personal de Salina de Lobos y estudiantes de ITVY.<em> Foto: Germ\u00e1n Leyva-Garc\u00eda.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236261727{margin-bottom: 0px !important;}&#8221;]El trabajo en Salina de Lobos representa la disposici\u00f3n de los diversos actores para la conservaci\u00f3n de las aves playeras, y aves acu\u00e1ticas en general. Esperamos que en el mediano y largo plazo se pueda apreciar el \u00e9xito de la implementaci\u00f3n de estas actividades, y se pueda continuar el arduo proceso de conservaci\u00f3n tanto en la Salina como\u00a0 del sitio RHRAP \/ WHSRN. La salina de Lobos se encuentra justo en el l\u00edmite sur del pol\u00edgono del sitio RHRAP\/WHSRN Bah\u00eda de Lobos. El ampliar el pol\u00edgono e incluirla dentro del sitio RHRAP\/WHSRN ser\u00eda importante en el esfuerzo de conservaci\u00f3n dentro de la Red, as\u00ed como un est\u00edmulo de la colaboraci\u00f3n de la iniciativa privada para el mejoramiento del h\u00e1bitat costero.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto de portada: Panor\u00e1mica de un estanque de evaporaci\u00f3n y la presencia de aves acu\u00e1ticas. <em>Foto: Germ\u00e1n Leyva-Garc\u00eda.<\/em><\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Germ\u00e1n Leyva &#8211; Centro de Investigaci\u00f3n en Alimentaci\u00f3n y Desarrollo \u2013 CIAD. Sonora, M\u00e9xico [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236066252{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]De los grupos biol\u00f3gicos m\u00e1s afectados por la degradaci\u00f3n de los humedales costeros [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":17035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,78,528],"tags":[],"class_list":["post-17037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-noticias-de-los-sitios","category-whsrn-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Germ\u00e1n Leyva &#8211; Centro de Investigaci\u00f3n en Alimentaci\u00f3n y Desarrollo \u2013 CIAD. Sonora, M\u00e9xico [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236066252{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]De los grupos biol\u00f3gicos m\u00e1s afectados por la degradaci\u00f3n de los humedales costeros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T19:08:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T15:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guest Author\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor Invitado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/\"},\"author\":{\"name\":\"Guest Author\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/99cbcafd1a567d9e50eed8268171f392\"},\"headline\":\"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico\",\"datePublished\":\"2022-02-28T19:08:01+00:00\",\"dateModified\":\"2022-03-02T15:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/\"},\"wordCount\":1555,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bahialobos_featuredimage.jpg\",\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Noticias de los Sitios\",\"WHSRN\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/\",\"name\":\"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bahialobos_featuredimage.jpg\",\"datePublished\":\"2022-02-28T19:08:01+00:00\",\"dateModified\":\"2022-03-02T15:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bahialobos_featuredimage.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bahialobos_featuredimage.jpg\",\"width\":1680,\"height\":775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/99cbcafd1a567d9e50eed8268171f392\",\"name\":\"Guest Author\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g\",\"caption\":\"Guest Author\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/guest_author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Germ\u00e1n Leyva &#8211; Centro de Investigaci\u00f3n en Alimentaci\u00f3n y Desarrollo \u2013 CIAD. Sonora, M\u00e9xico [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1646236066252{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]De los grupos biol\u00f3gicos m\u00e1s afectados por la degradaci\u00f3n de los humedales costeros [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2022-02-28T19:08:01+00:00","article_modified_time":"2022-03-02T15:51:09+00:00","og_image":[{"width":1680,"height":775,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg","type":"image\/jpeg"}],"author":"Guest Author","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Autor Invitado","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/"},"author":{"name":"Guest Author","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/99cbcafd1a567d9e50eed8268171f392"},"headline":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico","datePublished":"2022-02-28T19:08:01+00:00","dateModified":"2022-03-02T15:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/"},"wordCount":1555,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg","articleSection":["Conservaci\u00f3n en Acci\u00f3n","Noticias de los Sitios","WHSRN"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/","url":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/","name":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg","datePublished":"2022-02-28T19:08:01+00:00","dateModified":"2022-03-02T15:51:09+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2022\/02\/bahialobos_featuredimage.jpg","width":1680,"height":775},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/impulsando-acciones-para-la-conservacion-de-las-aves-playeras-en-la-salina-de-lobos-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Impulsando Acciones para la Conservaci\u00f3n de las Aves Playeras en la Salina de Lobos, M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/99cbcafd1a567d9e50eed8268171f392","name":"Guest Author","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca84b6d3d5b3da7d54ce4d70b9df4e6e90c94b02f10f5339df50afb959a39bef?s=96&d=mm&r=g","caption":"Guest Author"},"url":"https:\/\/whsrn.org\/es\/author\/guest_author\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/17037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=17037"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/17037\/revisions"}],"predecessor-version":[{"id":17081,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/17037\/revisions\/17081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/17035"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=17037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=17037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=17037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}