{"id":14370,"date":"2020-11-16T14:42:51","date_gmt":"2020-11-16T14:42:51","guid":{"rendered":"https:\/\/whsrn.org\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/"},"modified":"2020-11-18T21:07:00","modified_gmt":"2020-11-18T21:07:00","slug":"actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/","title":{"rendered":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\"><strong>Por Tjalle Boorsma &#8211; Asociaci\u00f3n Armon\u00eda<\/strong><\/p>\n<\/div>\n<div id=\"comp-jlcre5gq\" class=\"wp2\" title=\"\" data-exact-height=\"450\" data-content-padding-horizontal=\"0\" data-content-padding-vertical=\"0\">\n<div id=\"comp-jlcre5gqlink\" class=\"wp2link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1605733470689{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]La \u00e9poca seca boliviana ha llegado a la sabana del Beni conocida localmente como los Llanos de Moxos. Ocho meses de inundaciones (noviembre-julio) son reemplazados por cuatro meses de sequ\u00eda extrema (julio-noviembre). \u00c9ste tambi\u00e9n es el per\u00edodo en el que el Playero Acanelado (<em>Calidris subruficollis<\/em>) y otras aves playeras llegan a estos pastizales naturales bolivianos para alimentarse, descansar y prepararse para su tramo final de la migraci\u00f3n hacia el sur, y as\u00ed llegar a sus tierras de invernada.<\/p>\n<p>La Asociaci\u00f3n Armon\u00eda, la ONG l\u00edder en conservaci\u00f3n de aves en Bolivia, cre\u00f3 en el 2008 la Reserva Natural Barba Azul en el coraz\u00f3n de los Llanos de Moxos. En Barba Azul, Armon\u00eda est\u00e1 protegiendo h\u00e1bitat clave para el ave end\u00e9mica Paraba Barba Azul (<em>Ara glaucogularis<\/em>) pero tambi\u00e9n se han encontrado\u00a0 en septiembre grandes concentraciones de aves playeras usando pasto corto al borde del r\u00edo, incluyendo al Playeros Acanelado. Debido a los grandes n\u00fameros de esta especie usando Barba Azul como un punto de parada importante, la reserva fue declarada en 2015 como un sitio de Importancia Regional dentro de la Red Hemisf\u00e9rica de Reservas para Aves Playeras (RHRAP \/ WHSRN por sus siglas en ingl\u00e9s). A trav\u00e9s del apoyo del programa de subsidios de La Ley para la Conservaci\u00f3n de las Aves Migratorias Neotropicales (NMBCA por sus siglas en ingl\u00e9s) del Servicio de Pesca y Vida Silvestre de los Estados Unidos (USFWS por sus siglas en ingl\u00e9s), Armon\u00eda comenz\u00f3 a monitorear sistem\u00e1ticamente a las aves playeras desde 2014 y ahora administra una base de datos de siete a\u00f1os sobre la migraci\u00f3n de aves playeras en la Reserva Natural Barba Azul.<\/p>\n<p>La Reserva Natural Barba Azul tiene solo 11.000 hect\u00e1reas, mientras que los Llanos de Moxos son aproximadamente 12 millones de hect\u00e1reas incluyendo un complejo mosaico de pastizales sin \u00e1rboles, sabana tipo cerrado, sabana de palmeras, islas de bosque de palmeras, bosque de galer\u00eda a lo largo de r\u00edos de aguas blancas, humedales herb\u00e1ceos y lagos poco profundos.<\/p>\n<p>En 2016, se observ\u00f3 en un solo d\u00eda un total de 1.460 Playeros Acanelado (2,5% de la poblaci\u00f3n mundial). Pero m\u00e1s Playeros Acanelados deben estar usando los Llanos de Moxos en su migraci\u00f3n hacia el sur. Adem\u00e1s de los Playeros Acanelados, un gran n\u00famero de Playero Pectoral (<em>Calidris melanotos<\/em>), Playero Batit\u00fa (<em>Bartramia longicauda<\/em>) y, en menor medida, del Chorlo Dorado Americano (<em>Pluvialis dominica<\/em>) utilizan esta ecorregi\u00f3n durante su migraci\u00f3n hacia el sur (Herzog <em>et. al. <\/em>sin publicar).[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2020\/11\/3_barbaazul-2.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Playero Acanelado usa los Llanos de Moxos solo durante su migraci\u00f3n hacia el sur. Esto se debe a que Los Llanos de Moxos se encuentran en la \u00e9poca seca en septiembre, lo que proporciona un h\u00e1bitat de alimentaci\u00f3n suficiente. En su migraci\u00f3n hacia el norte, los Llanos de Moxos est\u00e1n completamente inundados y hay poco h\u00e1bitat de alimentaci\u00f3n disponible. Por lo tanto, se saltan Bolivia y vuelan directamente a los Llanos de Colombia y Venezuela que se encuentran en ese momento espec\u00edfico en la temporada seca. <em>Foto: Teo Camacho<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1605733591666{margin-bottom: 0px !important;}&#8221;]\n<div id=\"comp-jhgnp0bu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"84\">\n<div id=\"comp-jivjchlb\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"40\">\n<p>El equipo de monitoreo de aves playeras de Armon\u00eda viaj\u00f3 a Barba Azul el 28 de agosto de este a\u00f1o para monitorear aves playeras migratorias de larga distancia durante 30 d\u00edas en cinco lugares diferentes dentro de la reserva. El equipo recopil\u00f3 datos sobre la presencia\/ausencia de aves playeras, pero tambi\u00e9n otros factores ambientales para comprender mejor la preferencia de alimentaci\u00f3n de las aves playeras en sitios espec\u00edficos (longitud del pasto, presencia\/ausencia de ganado, n\u00famero de montones de esti\u00e9rcol, distancia al bosque, cobertura del pasto, etc.). Los resultados preliminares demostraron conteos que variaron desde 15 (m\u00ednimo) a 322 (m\u00e1ximo) individuos de Playeros Acanelado.<\/p>\n<p>Desafortunadamente, en 2019 se aprobaron nuevas leyes de reforma del uso de la tierra para convertir el 83% de los pastizales naturales y el h\u00e1bitat de los pantanos a campos de arroz y soja en los Llanos de Moxos, lo que amenaza el h\u00e1bitat natural de alimentaci\u00f3n de las aves playeras migratorias de larga distancia. Por lo tanto, es urgente comprender el uso y la selecci\u00f3n de h\u00e1bitats por parte del Playero Acanelado en este sistema de pastizales naturales y evaluar las \u00e1reas que son prioritarias a esa escala.<\/p>\n<p>Armon\u00eda est\u00e1 impulsando la conservaci\u00f3n a escala del paisaje m\u00e1s all\u00e1 de las fronteras de sus reservas para Paraba Barba Azul. Especies amenazadas como el Paraba Barba Azul y el Playero Acanelado comparten h\u00e1bitat la ganader\u00eda privada, la econom\u00eda m\u00e1s sustancial de esta regi\u00f3n y, por lo tanto, el actor m\u00e1s crucial. La creaci\u00f3n de reservas protegidas que conservan el h\u00e1bitat esencial es una estrategia importante, pero m\u00e1s importante es la creaci\u00f3n de estrategias de desarrollo sostenible, como la ganader\u00eda ecol\u00f3gica, para asegurar una conservaci\u00f3n a escala del paisaje.<\/p>\n<p>La estrategia de conservaci\u00f3n es convencer a estas partes interesadas con mentalidad empresarial para que adopten t\u00e9cnicas de ganader\u00eda con mejores pr\u00e1cticas sostenibles. Esto se hace demostrando resultados pr\u00e1cticos a trav\u00e9s del rancho modelo Barba Azul que Armon\u00eda est\u00e1 estableciendo, demostrando una mayor productividad e ingresos econ\u00f3micos, al mismo tiempo que protege el h\u00e1bitat. Proteger el h\u00e1bitat es proteger los activos financieros de un rancho. Trabajar junto con los ganaderos es clave para proteger los Llanos de Moxos y garantizar un h\u00e1bitat a escala de paisaje seguro para las aves playeras.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2020\/11\/3_barbaazul-1.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Equipo de campo camino a Barba Azul siguiendo las medidas de seguridad para el COVID-19. <em>Foto: Teodoro Camacho<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#3d4045&#8243; size=&#8221;12&#8243; font_weight=&#8221;400&#8243; font_family=&#8221;none&#8221;]<strong>Foto portada: Playero Acanelado en la Reserva Natural Barba Azul.<em>Foto: Daniel Alarc\u00f3n.<\/em> <\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Tjalle Boorsma &#8211; Asociaci\u00f3n Armon\u00eda [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1605733470689{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]La \u00e9poca seca boliviana ha llegado a la sabana del Beni conocida localmente como los Llanos de Moxos. Ocho meses de inundaciones [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[78,528],"tags":[60],"class_list":["post-14370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-los-sitios","category-whsrn-es","tag-grasslands"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Tjalle Boorsma &#8211; Asociaci\u00f3n Armon\u00eda [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1605733470689{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]La \u00e9poca seca boliviana ha llegado a la sabana del Beni conocida localmente como los Llanos de Moxos. Ocho meses de inundaciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-16T14:42:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-18T21:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WHSRN Executive Office\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oficina Ejecutiva de WHSRN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/\"},\"author\":{\"name\":\"WHSRN Executive Office\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\"},\"headline\":\"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul\",\"datePublished\":\"2020-11-16T14:42:51+00:00\",\"dateModified\":\"2020-11-18T21:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/\"},\"wordCount\":1243,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/barbaazul_new.jpg\",\"keywords\":[\"Grasslands\"],\"articleSection\":[\"Noticias de los Sitios\",\"WHSRN\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/\",\"name\":\"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/barbaazul_new.jpg\",\"datePublished\":\"2020-11-16T14:42:51+00:00\",\"dateModified\":\"2020-11-18T21:07:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/barbaazul_new.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/barbaazul_new.jpg\",\"width\":1680,\"height\":775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\",\"name\":\"WHSRN Executive Office\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"caption\":\"WHSRN Executive Office\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/whsrn-executive-office\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/","og_locale":"es_ES","og_type":"article","og_title":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul","og_description":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;] Por Tjalle Boorsma &#8211; Asociaci\u00f3n Armon\u00eda [\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1605733470689{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]La \u00e9poca seca boliviana ha llegado a la sabana del Beni conocida localmente como los Llanos de Moxos. Ocho meses de inundaciones [&hellip;]","og_url":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2020-11-16T14:42:51+00:00","article_modified_time":"2020-11-18T21:07:00+00:00","og_image":[{"width":1680,"height":775,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg","type":"image\/jpeg"}],"author":"WHSRN Executive Office","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Oficina Ejecutiva de WHSRN","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/"},"author":{"name":"WHSRN Executive Office","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1"},"headline":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul","datePublished":"2020-11-16T14:42:51+00:00","dateModified":"2020-11-18T21:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/"},"wordCount":1243,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg","keywords":["Grasslands"],"articleSection":["Noticias de los Sitios","WHSRN"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/","url":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/","name":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg","datePublished":"2020-11-16T14:42:51+00:00","dateModified":"2020-11-18T21:07:00+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/barbaazul_new.jpg","width":1680,"height":775},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/actualizacion-del-unico-sitio-whsrn-en-bolivia-la-reserva-natural-barba-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Actualizaci\u00f3n del \u00fanico sitio WHSRN en Bolivia: la Reserva Natural Barba Azul"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1","name":"WHSRN Executive Office","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","caption":"WHSRN Executive Office"},"url":"https:\/\/whsrn.org\/es\/author\/whsrn-executive-office\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/14370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=14370"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/14370\/revisions"}],"predecessor-version":[{"id":14413,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/14370\/revisions\/14413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/2827"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=14370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=14370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=14370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}