{"id":13165,"date":"2020-04-30T09:35:02","date_gmt":"2020-04-30T09:35:02","guid":{"rendered":"https:\/\/whsrn.org\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/"},"modified":"2020-04-30T13:58:51","modified_gmt":"2020-04-30T13:58:51","slug":"mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/","title":{"rendered":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1588041738954{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]En enero de 2019, una &#8220;bandada&#8221; de m\u00e1s de 500 entusiastas voluntarios de las aves playeras cens\u00f3 playas, planos lodosos, dunas y estuarios desde el norte de Per\u00fa, alrededor de la punta de las Am\u00e9ricas (Cabo de Hornos) y hasta el sur de Brasil. \u00bfLa meta? Comprender mejor la distribuci\u00f3n y abundancia de aves playeras a lo largo de las costas del Pac\u00edfico y el Atl\u00e1ntico del sur de Suram\u00e9rica, e identificar sitios clave para su conservaci\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/surveys_wpimg1.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Dos Playeros Blancos (Calidris alba) forrajeando en el sitio WHSRN &#8220;Reserva Nacional Paracas&#8221; en Per\u00fa. El Playero Blanco fue la especie m\u00e1s numerosa durante el censo costero. <em>Foto: Arne Lesterhuis.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1588041795807{margin-bottom: 0px !important;}&#8221;]Los censistas siguieron el protocolo desarrollado por el <a href=\"https:\/\/www.shorebirdplan.org\/science\/program-for-regional-and-international-shorebird-monitoring\/\">Programa de Monitoreo Regional e Internacional de Aves Playeras (PRISM, por sus siglas en ingl\u00e9s)<\/a>, y utilizado anteriormente para los censos costeros en Per\u00fa (en 2010 y 2014) y Chile (2014). Los resultados de esos censos se publicaron como atlas de aves playeras (<a href=\"http:\/\/www.minam.gob.pe\/diversidadbiologica\/wp-content\/uploads\/sites\/21\/2014\/02\/Atlas-de-las-Aves-Playeras-del-Per%C3%BA-FINAL-WEB.compressed.pdf\">Per\u00fa &#8211; Senner &amp; Angulo 2014<\/a>; Chile &#8211; <a href=\"http:\/\/www.redobservadores.cl\/wp-content\/uploads\/2018\/05\/Atlas-de-las-aves-playeras-de-Chile.pdf\">Garcia-Walther <em>et al.<\/em> 2017<\/a>). Ambos atlas mostraron que los censos exhaustivos de aves playeras son una herramienta excelente para ayudar a establecer estimaciones poblacionales a nivel nacional e identificar sitios importantes. Pero quiz\u00e1s lo m\u00e1s importante es la oportunidad que brindan los censos de involucrar a voluntarios, ayudando a construir una amplia &#8220;comunidad de apoyo&#8221; para el monitoreo y la conservaci\u00f3n de aves playeras.<\/p>\n<p>El \u00e9xito de los censos en Per\u00fa y Chile despert\u00f3 el inter\u00e9s en expandir los esfuerzos hacia la costa Atl\u00e1ntica, lo que fue posible en enero de 2019 a trav\u00e9s de una contribuci\u00f3n de la Ley de Conservaci\u00f3n de Aves Migratorias Neotropicales (NMBCA, por sus siglas en ingl\u00e9s). Para preparar a los voluntarios antes del censo, se realizaron 20 talleres (incluyendo seminarios web en l\u00ednea) en los cinco pa\u00edses participantes, capacitando a un total de 306 voluntarios en la identificaci\u00f3n de aves playeras y el protocolo del censo.[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/surveys_wpimg2.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/surveys_wpimg3.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5gi\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Izquierda: El Chorlito Malvinero (<em>Charadrius falklandicus<\/em>), fotografiado en el sitio WHSRN &#8220;Estuario del R\u00edo Gallegos&#8221; en Argentina, fue una de las especies residentes m\u00e1s comunes durante el censo costero del sur de Suram\u00e9rica. Derecha: Un Zarapito Trinador (<em>Numenius phaeopus<\/em>), una migratoria observada frecuentemente durante el censso costero, aqu\u00ed con el sitio WHSRN &#8220;Reserva Nacional Paracas&#8221; en el fondo. <em>Fotos: Arne Lesterhuis.<\/em><\/p>\n<\/div>\n<div id=\"comp-jlcre5gq\" class=\"wp2\" title=\"\" data-exact-height=\"450\" data-content-padding-horizontal=\"0\" data-content-padding-vertical=\"0\">\n<div id=\"comp-jlcre5gqlink\" class=\"wp2link\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][mk_padding_divider size=&#8221;20&#8243;][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1588041897089{margin-bottom: 0px !important;}&#8221;]Un n\u00famero impresionante de 532 voluntarios censaron aves playeras en un total de 300 sitios, cubriendo casi 1.000 puntos de conteo, y muestreando una longitud total de la costa de aproximadamente 11.000 km (6.835 millas). Se contaron un total de 128.462 aves playeras de 47 especies. De estas, 26 especies se reproducen en Norteam\u00e9rica, 20 en Suram\u00e9rica y una en la Ant\u00e1rtida. De las aves que se reproducen en Norteam\u00e9rica, las especies m\u00e1s numerosas fueron Playero Blanco (<em>Calidris alba<\/em>) (27.140 individuos), Playero Rabiblanco (<em>C. fuscicollis<\/em>) (10.866), Zarapito de Pico Recto (<em>Limosa haemastica<\/em>) (8.836) y Zarapito Trinador (<em>Numenius phaeopus<\/em>) (6.255). Entre las especies residentes, las m\u00e1s comunes fueron la Cig\u00fce\u00f1uela Com\u00fan (<em>Himantopus mexicanus<\/em>) (6.498 individuos), el Ostrero Americano (<em>Haematopus palliatus<\/em>) (5.429) y el Chorlito Malvinero (<em>Charadrius falklandicus<\/em>) (5.023). Los censos se realizaron en 16 sitios de la Red Hemisf\u00e9rica de Reservas para Aves Playeras (WHSRN por sus siglas en ingl\u00e9s), mientras que los resultados identificaron 13 sitios como sitios WHSRN potenciales, donde el conteo de al menos una especie de ave playera alcanz\u00f3 el 1% o m\u00e1s de la poblaci\u00f3n biogeogr\u00e1fica.<\/p>\n<p>Actualmente, los datos se est\u00e1n analizando para generar estimaciones de las poblaciones de aves playeras no reproductivas a lo largo de la costa sur de Suram\u00e9rica. Este trabajo es liderado por Nathan Senner, Ph.D. (Senner Lab, Departamento de Ciencias Biol\u00f3gicas de la Universidad de Carolina del Sur), co-coordinador de este censo y las dos versiones anteriores, y con la asistencia de sus estudiantes de Doctorado Juli\u00e1n Garc\u00eda-Walther y Fernando Faria. \u00a1Est\u00e9n atentos para m\u00e1s informaci\u00f3n![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][mk_fancy_title font_family=&#8221;none&#8221;]<strong>Foto de portada: <\/strong><strong>Un grupo de voluntarios que lleva a cabo el censo costero en Bah\u00eda de San Antonio. <em>Photo: Mirta Carbajal.<\/em><\/strong>[\/mk_fancy_title][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.<\/p>\n","protected":false},"author":6,"featured_media":13105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[418,172,528],"tags":[],"class_list":["post-13165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conectando-sitios-es","category-monitoreo-de-poblaciones","category-whsrn-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica<\/title>\n<meta name=\"description\" content=\"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-30T09:35:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-30T13:58:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arne Lesterhuis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arne Lesterhuis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/\"},\"author\":{\"name\":\"Arne Lesterhuis\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/a9c843046e3f5d70c4976364283125ce\"},\"headline\":\"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica\",\"datePublished\":\"2020-04-30T09:35:02+00:00\",\"dateModified\":\"2020-04-30T13:58:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/\"},\"wordCount\":979,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/csurveys_wpfeatured.jpg\",\"articleSection\":[\"Conectando Sitios\",\"Monitoreo de Poblaciones\",\"WHSRN\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/\",\"name\":\"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/csurveys_wpfeatured.jpg\",\"datePublished\":\"2020-04-30T09:35:02+00:00\",\"dateModified\":\"2020-04-30T13:58:51+00:00\",\"description\":\"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/csurveys_wpfeatured.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/csurveys_wpfeatured.jpg\",\"width\":1680,\"height\":775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/a9c843046e3f5d70c4976364283125ce\",\"name\":\"Arne Lesterhuis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g\",\"caption\":\"Arne Lesterhuis\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/alesterhuis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica","description":"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica","og_description":"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.","og_url":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2020-04-30T09:35:02+00:00","article_modified_time":"2020-04-30T13:58:51+00:00","og_image":[{"width":1680,"height":775,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg","type":"image\/jpeg"}],"author":"Arne Lesterhuis","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Arne Lesterhuis","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/"},"author":{"name":"Arne Lesterhuis","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/a9c843046e3f5d70c4976364283125ce"},"headline":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica","datePublished":"2020-04-30T09:35:02+00:00","dateModified":"2020-04-30T13:58:51+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/"},"wordCount":979,"commentCount":0,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg","articleSection":["Conectando Sitios","Monitoreo de Poblaciones","WHSRN"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/","url":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/","name":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg","datePublished":"2020-04-30T09:35:02+00:00","dateModified":"2020-04-30T13:58:51+00:00","description":"M\u00e1s de 500 voluntarios participaron del censo costero del sur de Suram\u00e9rica, para comprender mejor la distribuci\u00f3n de aves playeras y los esfuerzos futuros de conservaci\u00f3n.","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2020\/04\/csurveys_wpfeatured.jpg","width":1680,"height":775},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/mas-de-500-voluntarios-censan-las-aves-playeras-de-la-costa-del-sur-de-suramerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 500 Voluntarios Censan las Aves Playeras de la Costa del Sur de Suram\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/a9c843046e3f5d70c4976364283125ce","name":"Arne Lesterhuis","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eeb0932f7ac54dceb71f8d9348b13ef5e4c7fc47dda3f65a24cf9ef56512491?s=96&d=mm&r=g","caption":"Arne Lesterhuis"},"url":"https:\/\/whsrn.org\/es\/author\/alesterhuis\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/13165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=13165"}],"version-history":[{"count":1,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/13165\/revisions"}],"predecessor-version":[{"id":13166,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/13165\/revisions\/13166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/13105"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=13165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=13165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=13165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}