{"id":1190,"date":"2018-09-27T12:59:48","date_gmt":"2018-09-27T12:59:48","guid":{"rendered":"https:\/\/whsrn.org\/?p=1190"},"modified":"2019-03-12T19:04:45","modified_gmt":"2019-03-12T19:04:45","slug":"bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/","title":{"rendered":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza."},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text align=&#8221;center&#8221; css=&#8221;.vc_custom_1539867565634{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]\n<p class=\"font_8\" style=\"text-align: left;\"><strong>El jueves 9 de agosto, representantes de este sitio cr\u00edtico de aves playeras presentaron una propuesta oficial a la Ministra de Medio Ambiente de Chile, Marcela Cubillos<\/strong><\/p>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1552417459201{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]\n<p class=\"font_8\">En la desembocadura oriental del estrecho de Magallanes, en la costa chilena de Tierra del Fuego, la extensi\u00f3n de marismas en Bah\u00eda Lomas es la zona de invernada m\u00e1s importante para la subespecie rufa del Playero \u00e1rctico (<em>Calidris canutus rufa<\/em>) en toda Am\u00e9rica del Sur. Estos playeros vuelan 9,500 millas (15,000 kil\u00f3metros) para llegar a esta playa, viajando desde sus \u00e1reas de reproducci\u00f3n en el \u00c1rtico canadiense. El Playero \u00e1rctico no es la \u00fanica ave playera migratoria de larga distancia que cuenta con Bah\u00eda Lomas como un lugar seguro para llegar. Es el segundo sitio m\u00e1s importante en Sudam\u00e9rica para el Zarapito pico recto (<em>Limosa haemastica<\/em>), y tambi\u00e9n una zona de invernada crucial para el Playero de lomo blanco (<em>Calidris fuscicollis<\/em>).<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section full_width=&#8221;true&#8221; padding_top=&#8221;25&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683611141{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/baha-lomas_37.png&#8221; image_width=&#8221;1200&#8243; image_height=&#8221;750&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1536683620659{margin-right: 0px !important;margin-left: 0px !important;padding-right: 3px !important;padding-left: 3px !important;}&#8221;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/calidris-canutus.png&#8221; image_width=&#8221;1200&#8243; image_height=&#8221;750&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jivjchjf\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jmju2rqx\" class=\"txtNew\" data-packed=\"true\">\n<p class=\"font_9\">Izquierda:\u00a0Calidris fuscicollis\u00a0en\u00a0Bah\u00eda Lomas. <em>Foto: Diego Luna Quevedo.<\/em> Derecha: Una bandada de\u00a0Calidris canutus rufa\u00a0vista durante censos a\u00e9reos en\u00a0Bah\u00eda Lomas. <em>Foto: Sr. Antonio Larrea.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][vc_column_text css=&#8221;.vc_custom_1541159570637{margin-bottom: 0px !important;}&#8221;]\n<div id=\"comp-jhgnp0bu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"84\">\n<div id=\"comp-jivjchlb\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"40\">\n<p class=\"font_8\">Bah\u00eda Lomas fue declarada Sitio Ramsar en 2004, y en 2009 se convirti\u00f3 en un Sitio de Importancia Hemisf\u00e9rica de la RHRAP por albergar a casi el 50% de la poblaci\u00f3n rufa del Playero \u00e1rctico. Despu\u00e9s de a\u00f1os de investigaci\u00f3n y colaboraci\u00f3n para comprender mejor la incomparable importancia de esta remota bah\u00eda, Bah\u00eda Lomas fue recientemente reconocida una vez m\u00e1s, esta vez un paso m\u00e1s cerca de salvaguardar el sitio con el estatus legal de \u00e1rea protegida.<\/p>\n<p class=\"font_8\">El 6 de agosto de 2018, Bah\u00eda Lomas fue anunciada como uno de los 40 humedales prioritarios en un ambicioso plan nacional para proteger la rica biodiversidad de los humedales de Chile. El Ministerio de Medio Ambiente de Chile se comprometi\u00f3 a otorgar a cada uno de estos 40 sitios un nivel de estatus de protecci\u00f3n para el 2022, garantizando colectivamente la gesti\u00f3n a largo plazo y la conservaci\u00f3n de m\u00e1s de 250,000 hect\u00e1reas de humedales.<\/p>\n<p class=\"font_8\">Siguiendo la corriente de esta victoria para la conservaci\u00f3n, Diego Luna Quevedo de la RHRAP y Carmen Espoz, Decana de la Facultad de Ciencias de la Universidad Santo Tom\u00e1s y directora del Centro Bah\u00eda Lomas, visitaron a la Ministra de Medio Ambiente de Chile pocos d\u00edas despu\u00e9s y le presentaron una solicitud oficial para declarar Bah\u00eda Lomas como Santuario de la Naturaleza.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6458.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jmjug5bz\" class=\"txtNew\" data-packed=\"true\">\n<p class=\"font_9\">Diego Luna Quevedo y Carmen Espoz presentan\u00a0a la Ministra de Medio Ambiente de Chile la\u00a0solicitud oficial para declarar Bah\u00eda Lomas como Santuario de la Naturaleza. <em>Foto: Diego Luna Quevedo.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1541159629703{margin-bottom: 0px !important;}&#8221;]\n<div id=\"comp-jivjchmc\" class=\"txtNew\" data-packed=\"false\">\n<p class=\"font_8\">\u201cEsta solicitud de Santuario se sustenta en m\u00e1s de 15 a\u00f1os de monitoreo de nuestra facultad junto a investigadores de Canad\u00e1 y Estados Unidos\u201d, dijo Espoz.<\/p>\n<p class=\"font_8\">Gracias al apoyo de la Ley de Conservaci\u00f3n de Aves Migratorias Neotropicales (NMBCA, por sus siglas en ingl\u00e9s), la Oficina Ejecutiva de la RHRAP y el programa de Recuperaci\u00f3n de Aves Playeras de Manomet han podido asociarse con Espoz y un equipo de organizaciones nacionales e internacionales en una serie de proyectos para estudiar y proteger Bah\u00eda Lomas.<\/p>\n<p class=\"font_8\">Entre 2011 y 2013, Espoz, el Ministerio del Medio Ambiente de Chile, y Diego Luna Quevedo de la RHRAP condujeron una serie de talleres, reuniones y presentaciones para reunir a cient\u00edficos, profesionales de la industria, tomadores de decisiones y propietarios de tierra locales. El grupo lleg\u00f3 a un consenso para declarar el \u00e1rea como un Santuario Nacional de la Naturaleza, y desarroll\u00f3 la l\u00ednea de base para la propuesta original. Parte de este proceso fue el establecimiento del Centro Bah\u00eda Lomas, que abri\u00f3 sus puertas en 2012. Ahora en la cercana Punta Arenas y como parte de la Facultad de Ciencias de la Universidad Santo Tom\u00e1s, el Centro sirve como un espacio comunitario de investigaci\u00f3n cient\u00edfica, educaci\u00f3n ambiental y divulgaci\u00f3n publica entorno a la conservaci\u00f3n de Bah\u00eda Lomas.<\/p>\n<p class=\"font_8\">Una de las amenazas claves para este h\u00e1bitat crucial para las aves playeras es una serie de plataformas petroleras activas alrededor del sitio, operadas por la Empresa Nacional de Petr\u00f3leo de Chile (ENAP). La Oficina Ejecutiva de la RHRAP facilit\u00f3 una evaluaci\u00f3n integral del riesgo de derrames de petr\u00f3leo, incluyendo recomendaciones para reducir esta amenaza, y desarrollar un plan de respuesta de emergencia en caso de un accidente como esos. ENAP es responsable de administrar una de las amenazas claves en Bah\u00eda Lomas, pero tambi\u00e9n es un socio imprescindible en el monitoreo a largo plazo de aves playeras en el sitio. ENAP permite realizar monitoreos a\u00e9reos cada enero proporcionando el uso de helic\u00f3pteros, combustible e incluso alimentos y alojamiento para los investigadores.<\/p>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/poster_es.jpg&#8221; image_size=&#8221;full&#8221;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jmjug5bz\" class=\"txtNew\" data-packed=\"true\">\n<p class=\"font_9\"><em>Foto: Sr. Antonio Larrea.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1541159676451{margin-bottom: 0px !important;}&#8221;]\n<p class=\"font_8\">A trav\u00e9s del Centro Bah\u00eda Lomas y el departamento de ciencias de la Universidad Santo Tom\u00e1s, Carmen Espoz tambi\u00e9n lidera un equipo de investigadores para monitorear aves playeras en el terreno. Ella ha dedicado su carrera cient\u00edfica a la comprensi\u00f3n de la comunidad de invertebrados en las marismas de Bah\u00eda Lomas. \u00bfQu\u00e9 comen los Playeros \u00e1rcticos y el Zarapito pico recto, y c\u00f3mo puede este conocimiento informar el manejo de esta \u00e1rea de alimentaci\u00f3n cr\u00edtica para las aves playeras migratorias? Los proyectos de monitoreo e investigaci\u00f3n como estos han ayudado a guiar la implementaci\u00f3n del plan de manejo del sitio, y apoyan la declaratoria de Bah\u00eda Lomas como Santuario Nacional de la Naturaleza.<\/p>\n<p class=\"font_8\">Este es \u201cun sitio de de alto inter\u00e9s para la ciencia y sin dudas el santuario contribuir\u00e1 a un mejor manejo y conservaci\u00f3n&#8221;, dice Espoz.<\/p>\n<p class=\"font_8\">\u201cEste es un paso m\u00e1s para dar al Humedal Bah\u00eda Lomas un nivel de protecci\u00f3n efectivo\u201d, dijo Marcela Cubillos, Ministra de Medio Ambiente de Chile. &#8220;Nos permite seguir avanzando en el compromiso de declarar como \u00e1rea protegida durante el gobierno del Presidente Pi\u00f1era los 40 humedales priorizados en el Plan Nacional\u201d. La propuesta est\u00e1 siendo revisada actualmente por el Ministerio de Medio Ambiente de Chile. Carmen Espoz y Diego Luna Quevedo esperan celebrar la declaraci\u00f3n de Bah\u00eda Lomas como Santuario de la Naturaleza este diciembre.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][mk_image src=&#8221;https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481.jpg&#8221; image_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/mk_page_section][vc_row][vc_column][vc_column_text margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1541159732349{margin-bottom: 0px !important;}&#8221;]\n<div id=\"comp-jmju2rtc\" class=\"txtNew\" data-packed=\"true\">\n<p class=\"font_8\">Por m\u00e1s informaci\u00f3n sobre este proceso escriba a Diego Luna Quevedo, Especialista en Conservaci\u00f3n de la RHRAP, Manomet Inc.;\u00a0<a href=\"mailto:diego.luna@manomet.org\" target=\"_self\" data-content=\"diego.luna@manomet.org\" data-type=\"mail\" rel=\"noopener noreferrer\">diego.luna@manomet.org<\/a><\/p>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>El sitio de invernada m\u00e1s importante de toda Sudam\u00e9rica para la sub-especie rufa del Playero rojizo est\u00e1 un paso m\u00e1s cerca del estatus legal de \u00e1rea protegida. El gobierno de Chile anunci\u00f3 recientemente que Bah\u00eda Lomas ser\u00e1 uno de los 40 sitios prioritarios en un plan nuevo para proteger los humedales de Chile. Adem\u00e1s, este sitio de la RHRAP ahora est\u00e1 en proceso de ser declarado como un Santuario de la Naturaleza.<\/p>\n","protected":false},"author":4,"featured_media":1196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,78],"tags":[390,498],"class_list":["post-1190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-noticias-de-los-sitios","tag-bahia-lomas-es","tag-playero-rojizo-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN\" \/>\n<meta property=\"og:description\" content=\"El sitio de invernada m\u00e1s importante de toda Sudam\u00e9rica para la sub-especie rufa del Playero rojizo est\u00e1 un paso m\u00e1s cerca del estatus legal de \u00e1rea protegida. El gobierno de Chile anunci\u00f3 recientemente que Bah\u00eda Lomas ser\u00e1 uno de los 40 sitios prioritarios en un plan nuevo para proteger los humedales de Chile. Adem\u00e1s, este sitio de la RHRAP ahora est\u00e1 en proceso de ser declarado como un Santuario de la Naturaleza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-27T12:59:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-12T19:04:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481-1024x720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WHSRN Executive Office\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oficina Ejecutiva de WHSRN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/\"},\"author\":{\"name\":\"WHSRN Executive Office\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\"},\"headline\":\"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza.\",\"datePublished\":\"2018-09-27T12:59:48+00:00\",\"dateModified\":\"2019-03-12T19:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/\"},\"wordCount\":1506,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dsc_6481.jpg\",\"keywords\":[\"Bah\u00eda Lomas\",\"Playero Rojizo\"],\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Noticias de los Sitios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/\",\"name\":\"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dsc_6481.jpg\",\"datePublished\":\"2018-09-27T12:59:48+00:00\",\"dateModified\":\"2019-03-12T19:04:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dsc_6481.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dsc_6481.jpg\",\"width\":2924,\"height\":2055},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/c7ee6c10dbcfbe11f60820ec07d7b4b1\",\"name\":\"WHSRN Executive Office\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g\",\"caption\":\"WHSRN Executive Office\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/whsrn-executive-office\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/","og_locale":"es_ES","og_type":"article","og_title":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN","og_description":"El sitio de invernada m\u00e1s importante de toda Sudam\u00e9rica para la sub-especie rufa del Playero rojizo est\u00e1 un paso m\u00e1s cerca del estatus legal de \u00e1rea protegida. El gobierno de Chile anunci\u00f3 recientemente que Bah\u00eda Lomas ser\u00e1 uno de los 40 sitios prioritarios en un plan nuevo para proteger los humedales de Chile. Adem\u00e1s, este sitio de la RHRAP ahora est\u00e1 en proceso de ser declarado como un Santuario de la Naturaleza.","og_url":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2018-09-27T12:59:48+00:00","article_modified_time":"2019-03-12T19:04:45+00:00","og_image":[{"width":1024,"height":720,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481-1024x720.jpg","type":"image\/jpeg"}],"author":"WHSRN Executive Office","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Oficina Ejecutiva de WHSRN","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/"},"author":{"name":"WHSRN Executive Office","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1"},"headline":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza.","datePublished":"2018-09-27T12:59:48+00:00","dateModified":"2019-03-12T19:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/"},"wordCount":1506,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481.jpg","keywords":["Bah\u00eda Lomas","Playero Rojizo"],"articleSection":["Conservaci\u00f3n en Acci\u00f3n","Noticias de los Sitios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/","url":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/","name":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza. &#8211; WHSRN","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481.jpg","datePublished":"2018-09-27T12:59:48+00:00","dateModified":"2019-03-12T19:04:45+00:00","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2018\/10\/dsc_6481.jpg","width":2924,"height":2055},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/bahia-lomas-busca-estatus-como-santuario-natural-de-la-naturaleza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Bah\u00eda Lomas busca estatus como santuario natural de la naturaleza."}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/c7ee6c10dbcfbe11f60820ec07d7b4b1","name":"WHSRN Executive Office","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1da8686c2097c20493a37ff7e703ac47e0e91dc3d7d34c325b80c54550ee84e4?s=96&d=mm&r=g","caption":"WHSRN Executive Office"},"url":"https:\/\/whsrn.org\/es\/author\/whsrn-executive-office\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":5,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"predecessor-version":[{"id":8190,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/1190\/revisions\/8190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/1196"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}