{"id":10578,"date":"2019-07-15T21:40:42","date_gmt":"2019-07-15T21:40:42","guid":{"rendered":"https:\/\/whsrn.org\/desde-el-campo-la-primavera-de-2019-en-la-bahia-de-delaware\/"},"modified":"2019-07-15T22:41:27","modified_gmt":"2019-07-15T22:41:27","slug":"primavera-de-2019-en-la-bahia-de-delaware","status":"publish","type":"post","link":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/","title":{"rendered":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1537359740219{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1537371217000{margin-top: 0px !important;padding-top: 0px !important;}&#8221;][mk_padding_divider size=&#8221;20&#8243;][vc_column_text align=&#8221;center&#8221; margin_bottom=&#8221;20&#8243; css=&#8221;.vc_custom_1563198570076{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]\n<h5 class=\"font_8\">Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Las aves playeras se agruparon en las playas, los Cangrejos Herradura se agolparon en el agua y voluntarios de lugares cercanos y lejanos tomaron acciones. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de la Red Hemisf\u00e9rica de Reservas para Aves Playeras.<\/h5>\n[\/vc_column_text][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column][mk_padding_divider][mk_gallery images=&#8221;10553,10551,10515,10517,10549,10547,10545,10543,10541,10539,10537,10535,10533,10531,10529,10527,10525,10523,10521,10519&#8243; style=&#8221;style1&#8243; height=&#8221;300&#8243; hover_scenarios=&#8221;grayscale&#8221;][\/vc_column][\/mk_page_section][vc_row][vc_column][mk_padding_divider size=&#8221;80&#8243;][\/vc_column][\/vc_row][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][vc_video link=&#8221;https:\/\/youtu.be\/hDbpzjgiqv0&#8243;][mk_padding_divider size=&#8221;20&#8243;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Este grupo de Calidris pusilla busca su pr\u00f3xima comida de huevos de Cangrejo Herradura.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][vc_video link=&#8221;https:\/\/youtu.be\/jr56hg2l8Wo&#8221;][mk_padding_divider size=&#8221;20&#8243;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Calidris canutus, Calidris alba, Arenaria interpres y Calidris pusilla comen los huevos de Cangrejo Herradura en la Bah\u00eda de Delaware.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][\/mk_page_section][mk_page_section min_height=&#8221;1&#8243; padding_bottom=&#8221;0&#8243; sidebar=&#8221;sidebar-1&#8243;][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][vc_video link=&#8221;https:\/\/youtu.be\/oRN1ZBSKLxs&#8221;][mk_padding_divider size=&#8221;20&#8243;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Muchas manos hacen el trabajo liviano cuando los estudiantes de la Escuela Superior Haddonfield Memorial participan.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][vc_column width=&#8221;1\/2&#8243;][mk_padding_divider][vc_video link=&#8221;https:\/\/youtu.be\/Zr3C0u0S7Vo&#8221;][mk_padding_divider size=&#8221;20&#8243;][mk_fancy_title tag_name=&#8221;span&#8221; color=&#8221;#53565a&#8221; size=&#8221;12&#8243; font_weight=&#8221;bold&#8221; margin_bottom=&#8221;0&#8243; font_family=&#8221;none&#8221; align=&#8221;center&#8221;]\n<div id=\"comp-jjabhjs7\" class=\"txtNew\" data-packed=\"true\">\n<div id=\"comp-jhgnp0bn\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<div id=\"comp-jlcre5hu\" class=\"txtNew\" data-packed=\"false\" data-min-height=\"17\">\n<p class=\"font_9\">Un giro r\u00e1pido bajo el sol caliente y este Cangrejo Herradura se dirige de vuelta al agua.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/mk_fancy_title][\/vc_column][\/mk_page_section]\n","protected":false},"excerpt":{"rendered":"<p>Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de la Red Hemisf\u00e9rica de Reservas para Aves Playeras.<\/p>\n","protected":false},"author":10,"featured_media":10510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[75,78],"tags":[],"class_list":["post-10578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservacion-en-accion","category-noticias-de-los-sitios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware<\/title>\n<meta name=\"description\" content=\"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware\" \/>\n<meta property=\"og:description\" content=\"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/\" \/>\n<meta property=\"og:site_name\" content=\"WHSRN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WHSRN\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T21:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-15T22:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1680\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Chamberlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:site\" content=\"@WHSRN\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Chamberlin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/\"},\"author\":{\"name\":\"Laura Chamberlin\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/89c8c7f68d90f6368e7a653b3cb6ac6a\"},\"headline\":\"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware\",\"datePublished\":\"2019-07-15T21:40:42+00:00\",\"dateModified\":\"2019-07-15T22:41:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hsc_featureimage.jpg\",\"articleSection\":[\"Conservaci\u00f3n en Acci\u00f3n\",\"Noticias de los Sitios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/\",\"name\":\"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hsc_featureimage.jpg\",\"datePublished\":\"2019-07-15T21:40:42+00:00\",\"dateModified\":\"2019-07-15T22:41:27+00:00\",\"description\":\"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hsc_featureimage.jpg\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hsc_featureimage.jpg\",\"width\":1680,\"height\":775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/primavera-de-2019-en-la-bahia-de-delaware\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"name\":\"WHSRN\",\"description\":\"Western Hemisphere Shorebird Reserve Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whsrn.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#organization\",\"name\":\"Western Hemisphere Shorebird Reserve Network\",\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"contentUrl\":\"https:\\\/\\\/whsrn.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/whsrn_nostrapline_square.png\",\"width\":800,\"height\":800,\"caption\":\"Western Hemisphere Shorebird Reserve Network\"},\"image\":{\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WHSRN\",\"https:\\\/\\\/x.com\\\/WHSRN\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDMz2oCsiK8e03UxFhHhdEA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whsrn.org\\\/es\\\/#\\\/schema\\\/person\\\/89c8c7f68d90f6368e7a653b3cb6ac6a\",\"name\":\"Laura Chamberlin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g\",\"caption\":\"Laura Chamberlin\"},\"url\":\"https:\\\/\\\/whsrn.org\\\/es\\\/author\\\/lchamberlin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware","description":"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/","og_locale":"es_ES","og_type":"article","og_title":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware","og_description":"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.","og_url":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/","og_site_name":"WHSRN","article_publisher":"https:\/\/www.facebook.com\/WHSRN","article_published_time":"2019-07-15T21:40:42+00:00","article_modified_time":"2019-07-15T22:41:27+00:00","og_image":[{"width":1680,"height":775,"url":"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg","type":"image\/jpeg"}],"author":"Laura Chamberlin","twitter_card":"summary_large_image","twitter_creator":"@WHSRN","twitter_site":"@WHSRN","twitter_misc":{"Escrito por":"Laura Chamberlin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#article","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/"},"author":{"name":"Laura Chamberlin","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/89c8c7f68d90f6368e7a653b3cb6ac6a"},"headline":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware","datePublished":"2019-07-15T21:40:42+00:00","dateModified":"2019-07-15T22:41:27+00:00","mainEntityOfPage":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"image":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg","articleSection":["Conservaci\u00f3n en Acci\u00f3n","Noticias de los Sitios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/","url":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/","name":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware","isPartOf":{"@id":"https:\/\/whsrn.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#primaryimage"},"image":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#primaryimage"},"thumbnailUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg","datePublished":"2019-07-15T21:40:42+00:00","dateModified":"2019-07-15T22:41:27+00:00","description":"Otra temporada de migraci\u00f3n de primavera ha acontecido en la Bah\u00eda de Delaware. Mire hacia atr\u00e1s con nosotros para celebrar la \u00e9poca m\u00e1s maravillosa del a\u00f1o en el primer sitio de WHSRN.","breadcrumb":{"@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#primaryimage","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2019\/07\/hsc_featureimage.jpg","width":1680,"height":775},{"@type":"BreadcrumbList","@id":"https:\/\/whsrn.org\/es\/primavera-de-2019-en-la-bahia-de-delaware\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whsrn.org\/es\/"},{"@type":"ListItem","position":2,"name":"Desde el Campo: la Primavera de 2019 en la Bah\u00eda de Delaware"}]},{"@type":"WebSite","@id":"https:\/\/whsrn.org\/es\/#website","url":"https:\/\/whsrn.org\/es\/","name":"WHSRN","description":"Western Hemisphere Shorebird Reserve Network","publisher":{"@id":"https:\/\/whsrn.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whsrn.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whsrn.org\/es\/#organization","name":"Western Hemisphere Shorebird Reserve Network","url":"https:\/\/whsrn.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","contentUrl":"https:\/\/whsrn.org\/wp-content\/uploads\/2021\/01\/whsrn_nostrapline_square.png","width":800,"height":800,"caption":"Western Hemisphere Shorebird Reserve Network"},"image":{"@id":"https:\/\/whsrn.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WHSRN","https:\/\/x.com\/WHSRN","https:\/\/www.youtube.com\/channel\/UCDMz2oCsiK8e03UxFhHhdEA"]},{"@type":"Person","@id":"https:\/\/whsrn.org\/es\/#\/schema\/person\/89c8c7f68d90f6368e7a653b3cb6ac6a","name":"Laura Chamberlin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f743ea7ce0cfd581bbd50e229f0ab6c1b70fad8433d1bec28fc6033bbeba719c?s=96&d=mm&r=g","caption":"Laura Chamberlin"},"url":"https:\/\/whsrn.org\/es\/author\/lchamberlin\/"}]}},"_links":{"self":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/10578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/comments?post=10578"}],"version-history":[{"count":4,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/10578\/revisions"}],"predecessor-version":[{"id":10589,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/posts\/10578\/revisions\/10589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media\/10510"}],"wp:attachment":[{"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/media?parent=10578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/categories?post=10578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whsrn.org\/es\/wp-json\/wp\/v2\/tags?post=10578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}